{"id":8083,"date":"2018-10-03T14:37:11","date_gmt":"2018-10-03T17:37:11","guid":{"rendered":"https:\/\/www.lasrosas.com.ar\/portal\/?p=8083"},"modified":"2018-10-03T14:37:26","modified_gmt":"2018-10-03T17:37:26","slug":"abstracta-presento-su-nueva-capsula-jb-pari","status":"publish","type":"post","link":"https:\/\/www.lasrosas.com.ar\/portal\/abstracta-presento-su-nueva-capsula-jb-pari\/","title":{"rendered":"ABSTRACTA PRESENT\u00d3 SU NUEVA C\u00c1PSULA \u00abJB PAR\u00cdS\u00bb"},"content":{"rendered":"<h3><strong>ABSTRACTA present\u00f3 en el local de Nuevocentro Shopping una nueva colecci\u00f3n c\u00e1psula con inspiraci\u00f3n parisina.<\/strong><\/h3>\n<p>La marca de ropa ABSTRACTA realiz\u00f3 una nueva alianza con el objetivo de\u00a0 proponer una mirada innovadora, fresca y femenina a sus clientas y amigas; es por esto que, se gesta la colecci\u00f3n c\u00e1psula junto a la cordobesa Jime Buttigliengo, reconocida referente de la moda internacional radicada en Par\u00eds.<\/p>\n<p>JB PARIS\u00a0 est\u00e1 compuesta por prendas que remiten al verano europeo, en las que se destaca su versatilidad, dise\u00f1o y cuidada elecci\u00f3n de g\u00e9neros.<\/p>\n<div>\n<div>\n<p>Jime se inspir\u00f3 en la Ciudad de la Luz, otorg\u00e1ndole a la colecci\u00f3n elegancia con ciertos gui\u00f1os urbanos en siluetas rectas y l\u00e1nguidas que cobran forma en monos, pantalones, tops remeras, camperas, jeans, bodys y blazers.<\/p>\n<p>Clientas y amigas de la marca, tuvieron la posibilidad de probarse los nuevos looks, mientras disfrutan de una rica limonada de frutos rojos y un macaron, o eligen algo de las m\u00faltiples propuestas de un cuidado catering lleno de gui\u00f1os parisinos.<\/p>\n<\/div>\n<div>\n<p>El customizado de las denim bag con patchs, es otro de los must del evento, mientras la artista Mary Barbosa interviene con marcadores en un trip primaveral, la inmensa vidriera del local.<\/p>\n<p>Como un pasaje directo a Champs Elysees, una playlist de m\u00fasica francesa\u00a0 y una colecci\u00f3n que destila charme y elegancia parisina para una mujer empoderada, ecl\u00e9ctica y exploradora del mundo, ABSTRACTA se abre a un universo experiencial y te invita a ser parte.<\/p>\n<\/div>\n<\/div>\n<div><\/div>\n<div>\n\r\n\t\t<style type='text\/css'>\r\n\t\t\t#gallery-1 {\r\n\t\t\t\tmargin: auto;\r\n\t\t\t}\r\n\t\t\t#gallery-1 .gallery-item {\r\n\t\t\t\tfloat: left;\r\n\t\t\t\tmargin-top: 10px;\r\n\t\t\t\ttext-align: center;\r\n\t\t\t\twidth: 33%;\r\n\t\t\t}\r\n\t\t\t#gallery-1 img {\r\n\t\t\t\tborder: 2px solid #cfcfcf;\r\n\t\t\t}\r\n\t\t\t#gallery-1 .gallery-caption {\r\n\t\t\t\tmargin-left: 0;\r\n\t\t\t}\r\n\t\t<\/style>\r\n\t\t<!-- see gallery_shortcode() in wp-includes\/media.php -->\n\t\t<div id='gallery-1' class='gallery galleryid-8083 gallery-columns-3 gallery-size-full gallery1'><script type=\"text\/javascript\">\r\n\/\/ <![CDATA[\r\n\tjQuery(document).ready(function () {\r\n\t\tjQuery(\".gallery1 a\").attr(\"rel\",\"gallery1\");\t\r\n\t\tjQuery('a[rel=\"gallery1\"]').colorbox({maxWidth:\"95%\", maxHeight:\"95%\",title: function(){ return jQuery(this).children().attr(\"alt\"); }, });\r\n\t});\r\n\/\/ ]]>\r\n<\/script>\n<dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6509.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6509.jpg\" width=\"1300\" height=\"868\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1300px; --smush-placeholder-aspect-ratio: 1300\/868;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6500.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6500.jpg\" width=\"1300\" height=\"868\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1300px; --smush-placeholder-aspect-ratio: 1300\/868;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6565-2.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6565-2.jpg\" width=\"1300\" height=\"868\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1300px; --smush-placeholder-aspect-ratio: 1300\/868;\" \/><\/a>\r\n<\/dt><\/dl><br style=\"clear: both\" \/><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6641-2.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6641-2.jpg\" width=\"868\" height=\"1300\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 868px; --smush-placeholder-aspect-ratio: 868\/1300;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6586-2.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6586-2.jpg\" width=\"868\" height=\"1300\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 868px; --smush-placeholder-aspect-ratio: 868\/1300;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6611-2.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6611-2.jpg\" width=\"1300\" height=\"868\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1300px; --smush-placeholder-aspect-ratio: 1300\/868;\" \/><\/a>\r\n<\/dt><\/dl><br style=\"clear: both\" \/><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6419.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6419.jpg\" width=\"1300\" height=\"868\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1300px; --smush-placeholder-aspect-ratio: 1300\/868;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6342.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6342.jpg\" width=\"1300\" height=\"868\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1300px; --smush-placeholder-aspect-ratio: 1300\/868;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6347.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_6347.jpg\" width=\"1300\" height=\"868\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1300px; --smush-placeholder-aspect-ratio: 1300\/868;\" \/><\/a>\r\n<\/dt><\/dl><br style=\"clear: both\" \/>\r\n\t\t<\/div>\n\n<\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>ABSTRACTA present\u00f3 en el local de Nuevocentro Shopping una nueva colecci\u00f3n c\u00e1psula con inspiraci\u00f3n parisina. La marca de ropa ABSTRACTA realiz\u00f3 una nueva alianza con el objetivo de\u00a0 proponer una mirada innovadora, fresca y femenina a sus clientas y amigas; es por esto que, se gesta la colecci\u00f3n c\u00e1psula junto a la cordobesa Jime Buttigliengo, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":8085,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[30],"tags":[],"class_list":["post-8083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-moda"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/8083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=8083"}],"version-history":[{"count":0,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/8083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media\/8085"}],"wp:attachment":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=8083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=8083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=8083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}