{"id":79774,"date":"2024-08-30T16:39:39","date_gmt":"2024-08-30T19:39:39","guid":{"rendered":"https:\/\/www.lasrosas.com.ar\/portal\/?p=79774"},"modified":"2024-08-30T16:39:41","modified_gmt":"2024-08-30T19:39:41","slug":"rapsodia-celebra-su-25-aniversario-con-una-exclusiva-dinner-party","status":"publish","type":"post","link":"https:\/\/www.lasrosas.com.ar\/portal\/rapsodia-celebra-su-25-aniversario-con-una-exclusiva-dinner-party\/","title":{"rendered":"RAPSODIA CELEBRA SU 25\u00b0 ANIVERSARIO CON UNA EXCLUSIVA DINNER PARTY"},"content":{"rendered":"\n<p>En el marco de su 25\u00b0 aniversario, Rapsodia celebr\u00f3 con una exclusiva dinner party que dio inicio a BAFWEEK, rindiendo homenaje a sus a\u00f1os de amor, rock y libertad. La marca deslumbr\u00f3 con una puesta en escena impactante, que incluy\u00f3 una mesa para 120 invitados al m\u00e1s puro estilo bohemio de Rapsodia. La cena tambi\u00e9n cont\u00f3 con la presentaci\u00f3n de su nueva colecci\u00f3n primavera-verano \u201cBohemian Rhapsody SS25\u201d en el Pabell\u00f3n Azul de La Rural, Av. Sarmiento 2704, CABA.<br><br>La velada comenz\u00f3 con un c\u00f3ctel que agasaj\u00f3 a los presentes, en donde se present\u00f3 una retrospectiva de 25 maniqu\u00edes exhibiendo looks ic\u00f3nicos de la marca. Un cortinado color arena ocultaba el majestuoso escenario principal del evento: una imponente mesa con iluminaci\u00f3n blanca, con un concepto de ambientaci\u00f3n inspirado en colores neutros siguiendo las tendencias internacionales, creando un lugar \u00fanico e inesperado. Una vez que los invitados finalizaron el primer plato, el desfile se convirti\u00f3 en el protagonista de la noche, la marca present\u00f3 su nueva colecci\u00f3n \u201cBohemian Rhapsody SS25\u201d. La puesta en escena transform\u00f3 el pabell\u00f3n en un escenario sin precedentes dise\u00f1ado por Sergio Lacroix<br><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1280\" height=\"1920\" data-id=\"79779\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-3-1280x1920.jpg\" alt=\"\" class=\"wp-image-79779 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-3-1280x1920.jpg 1280w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-3-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-3-1024x1536.jpg 1024w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-3-scaled.jpg 1365w\" data-sizes=\"(max-width: 1280px) 100vw, 1280px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1280px; --smush-placeholder-aspect-ratio: 1280\/1920;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1280\" height=\"1920\" data-id=\"79777\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-2-1-1280x1920.jpg\" alt=\"\" class=\"wp-image-79777 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-2-1-1280x1920.jpg 1280w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-2-1-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-2-1-1024x1536.jpg 1024w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-2-1-scaled.jpg 1365w\" data-sizes=\"(max-width: 1280px) 100vw, 1280px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1280px; --smush-placeholder-aspect-ratio: 1280\/1920;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1280\" height=\"1920\" data-id=\"79778\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-1-1280x1920.jpg\" alt=\"\" class=\"wp-image-79778 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-1-1280x1920.jpg 1280w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-1-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-1-1024x1536.jpg 1024w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-1-scaled.jpg 1365w\" data-sizes=\"(max-width: 1280px) 100vw, 1280px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1280px; --smush-placeholder-aspect-ratio: 1280\/1920;\" \/><\/figure>\n<\/figure>\n\n\n\n<p><br>\u201cBohemian Rhapsody SS25\u201d es una propuesta que rinde tributo al esp\u00edritu de la mujer moderna: libre, fresca, sensual y femenina. La colecci\u00f3n ofrece un viaje donde la bohemia y las etnias se entrecruzan en un escenario cargado de texturas y sutilezas. Los metalizados en variedad de dorados, detalles en brillos y cueros, encajes y bordados en batik se combinan en piezas \u00fanicas. La paleta de colores incluye tonos nude, tierra, ocre, kaki, verdes, morados y acentos de amarillo y orqu\u00eddea.<br><br>El denim, parte esencial de la identidad de Rapsodia, se renueva cada temporada con propuestas innovadoras. Este verano, se incorporan nuevos lavados, tejidos, siluetas y colores, junto con sutiles gui\u00f1os como brillos, apliques y remaches. <br><br>Entre los invitados se destacaron figuras reconocidas en el mundo de la moda y la m\u00fasica, as\u00ed como actrices y amigas cercanas de la marca. Delfina Chaves, Zaira Nara, Emma Horvilleur, Emilia Attias, Liz Solari, Mar\u00eda Campos, Sof\u00eda Zamolo, Chloe Bello, Charo Calamaro, Taina Gravier, Benicio Gravier, Lulu Cahen d\u2019Anvers, Paula Cahen d\u2019Anvers y Fini Bocchino fueron algunos de los celebrities presentes en la celebraci\u00f3n.<br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1920\" height=\"1280\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-6-1920x1280.jpg\" alt=\"\" class=\"wp-image-79781 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-6-1920x1280.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-6-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-6-1536x1024.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/BAFWEEK-Jornada-1-Rapsodia-6-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/figure>\n\n\n\n<p><br>Rapsodia, una vez m\u00e1s, captur\u00f3 la esencia vibrante y \u00fanica que ha caracterizado a la marca durante estos 25 a\u00f1os. Este evento no solo reafirm\u00f3 el ADN de Rapsodia, sino que tambi\u00e9n rindi\u00f3 homenaje a un estilo atemporal que sigue inspirando a diversas generaciones. As\u00ed, Rapsodia abri\u00f3 la semana m\u00e1s importante de la moda argentina, marcando el inicio con un evento lleno de expectativa y entusiasmo.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En el marco de su 25\u00b0 aniversario, Rapsodia celebr\u00f3 con una exclusiva dinner party que dio inicio a BAFWEEK, rindiendo homenaje a sus a\u00f1os de amor, rock y libertad. La marca deslumbr\u00f3 con una puesta en escena impactante, que incluy\u00f3 una mesa para 120 invitados al m\u00e1s puro estilo bohemio de Rapsodia. La cena tambi\u00e9n [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":79780,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[100,30],"tags":[448,728,58,76,78],"class_list":["post-79774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-moda","tag-bafweek","tag-indumentaria","tag-moda","tag-rapsodia","tag-ropa"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/79774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=79774"}],"version-history":[{"count":1,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/79774\/revisions"}],"predecessor-version":[{"id":79782,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/79774\/revisions\/79782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media\/79780"}],"wp:attachment":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=79774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=79774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=79774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}