{"id":79525,"date":"2024-08-11T12:34:56","date_gmt":"2024-08-11T15:34:56","guid":{"rendered":"https:\/\/www.lasrosas.com.ar\/portal\/?p=79525"},"modified":"2024-08-11T12:34:59","modified_gmt":"2024-08-11T15:34:59","slug":"pandora-adorna-la-pasarela-de-cphfw-colaborando-con-rotate-para-su-desfile-ss25","status":"publish","type":"post","link":"https:\/\/www.lasrosas.com.ar\/portal\/pandora-adorna-la-pasarela-de-cphfw-colaborando-con-rotate-para-su-desfile-ss25\/","title":{"rendered":"PANDORA ADORNA LA PASARELA DE CPHFW, COLABORANDO CON ROTATE PARA SU DESFILE SS25\u00a0"},"content":{"rendered":"\n<p>Pandora apareci\u00f3 por primera vez en la pasarela de la Semana de la Moda de su pa\u00eds de origen para colaborar con la marca de moda danesa ROTATE, en su desfile SS25, que tuvo lugar el bello Jard\u00edn de la Biblioteca Real.<\/p>\n\n\n\n<p>Asisti\u00f3 nada menos que la embajadora global de la marca Pandora, Pamela Anderson, ataviada con <em>Pandora<\/em> <em>Lab-Grown Diamonds, Moments y ESSENCE<\/em>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1920\" height=\"1280\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/Thora-Valdimars-y-Jeanette-Madsen-Directoras-creativas-y-Co-fundadoras-de-Rotatejunto-a-Pamela-Andreson-Embajadora-Global-de-Pandora-en-el-desfile-de-Rotate-en-el-marco-del-CPHFW-1920x1280.jpg\" alt=\"\" class=\"wp-image-79527 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/Thora-Valdimars-y-Jeanette-Madsen-Directoras-creativas-y-Co-fundadoras-de-Rotatejunto-a-Pamela-Andreson-Embajadora-Global-de-Pandora-en-el-desfile-de-Rotate-en-el-marco-del-CPHFW-1920x1280.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/Thora-Valdimars-y-Jeanette-Madsen-Directoras-creativas-y-Co-fundadoras-de-Rotatejunto-a-Pamela-Andreson-Embajadora-Global-de-Pandora-en-el-desfile-de-Rotate-en-el-marco-del-CPHFW-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/Thora-Valdimars-y-Jeanette-Madsen-Directoras-creativas-y-Co-fundadoras-de-Rotatejunto-a-Pamela-Andreson-Embajadora-Global-de-Pandora-en-el-desfile-de-Rotate-en-el-marco-del-CPHFW-1536x1024.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/Thora-Valdimars-y-Jeanette-Madsen-Directoras-creativas-y-Co-fundadoras-de-Rotatejunto-a-Pamela-Andreson-Embajadora-Global-de-Pandora-en-el-desfile-de-Rotate-en-el-marco-del-CPHFW-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><figcaption class=\"wp-element-caption\">COPENHAGEN, DENMARK &#8211; AUGUST 08: XX attends the ROTATE show during Copenhagen Fashion Week on August 08, 2024 in Copenhagen, Denmark. (Photo by Martin Sylvest Andersen\/Getty Images for PANDORA)<\/figcaption><\/figure>\n\n\n\n<p>Toni Garrn cerr\u00f3 la pasarela con un espectacular vestido hecho a mano por la artista Grete Henriette, con 2.000 brazaletes<em> Pandora Timeless Tennis<\/em>.<\/p>\n\n\n\n<p>Los brazaletes, aros y anillos de la colecci\u00f3n PANDORA ESSENCE dieron un toque inesperado a la gracia et\u00e9rea de la ropa, yuxtaponiendo los dise\u00f1os florales con formas esculturales y contornos org\u00e1nicos para un acabado incre\u00edblemente memorable.<\/p>\n\n\n\n<p>La artista Grete Henriette tambi\u00e9n aport\u00f3 su talento al espect\u00e1culo. Ella enlaz\u00f3 a mano 2.000 brazaletes<em> Pandora Timeless Tennis <\/em>plateados a un body ROTATE; as\u00ed como tambi\u00e9n realiz\u00f3 a mano una variedad de cinturones, collares y flores que adornaban las prendas, usando m\u00e1s de 300 collares <em>Pandora Moments 14K yellow gold-plated Rolo<\/em> para reflejar los motivos florales del espect\u00e1culo.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Pandora apareci\u00f3 por primera vez en la pasarela de la Semana de la Moda de su pa\u00eds de origen para colaborar con la marca de moda danesa ROTATE, en su desfile SS25, que tuvo lugar el bello Jard\u00edn de la Biblioteca Real. Asisti\u00f3 nada menos que la embajadora global de la marca Pandora, Pamela Anderson, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":79526,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[100,30],"tags":[222,537,58,457,879],"class_list":["post-79525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-moda","tag-desfile","tag-joyas","tag-moda","tag-pandora","tag-pasarela"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/79525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=79525"}],"version-history":[{"count":1,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/79525\/revisions"}],"predecessor-version":[{"id":79528,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/79525\/revisions\/79528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media\/79526"}],"wp:attachment":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=79525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=79525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=79525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}