{"id":7740,"date":"2018-09-24T10:36:33","date_gmt":"2018-09-24T13:36:33","guid":{"rendered":"https:\/\/www.lasrosas.com.ar\/portal\/?p=7740"},"modified":"2018-12-12T17:04:33","modified_gmt":"2018-12-12T20:04:33","slug":"mili-pineiro-model-colours","status":"publish","type":"post","link":"https:\/\/www.lasrosas.com.ar\/portal\/mili-pineiro-model-colours\/","title":{"rendered":"MILI PI\u00d1EIRO: MODEL COLOURS"},"content":{"rendered":"<h3><strong>\u00a0Mili es cordobesa, vive en Par\u00eds y es modelo de M\u00fanich Models. Arranc\u00f3 haciendo fotos planeando un intercambio en Par\u00eds. Fue modelo de grandes marcas como Chanel, Fendi y Levi\u00b4s. Conoc\u00e9 c\u00f3mo creci\u00f3 dentro del mundo fashion y todos los secretos en primera persona.<\/strong><\/h3>\n<hr \/>\n<p><strong><br \/>\n\u00bfConociste a\u00a0Karl Lagerfeld?\u00a0<\/strong><\/p>\n<p>S\u00ed, lo conoc\u00ed primero en los fittings del desfile. Primero ten\u00e9s el casting con la casting director, y si qued\u00e1s, ten\u00e9s el fitting. El segundo casting es con Karl y para eso te maquillan y te peinan como va a ser el H&amp;M del show. Eligen tu look y si Karl da el ok, hac\u00e9s el desfile.<\/p>\n<p>Siempre me acuerdo que la primera vez, despu\u00e9s de que me maquillaran, peinaran y vistieran, hab\u00eda 10 personas esperando que desfilara y Karl, justo ah\u00ed. \u00a1Casi me muero, no sab\u00eda c\u00f3mo disimular los nervios y la emoci\u00f3n! No ten\u00eda idea que lo iba a ver.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfC\u00f3mo es el mundo Chanel? <\/strong><\/p>\n<p>Chanel es una locura, un sue\u00f1o de pel\u00edcula. Cada show tiene un despliegue y una escenograf\u00eda que te deja sin palabras. Este a\u00f1o, trabaj\u00e9 casi dos meses todos los d\u00edas haciendo los fittings y looks de la pr\u00f3xima colecci\u00f3n. Eso me mostr\u00f3 c\u00f3mo funciona la creaci\u00f3n de la ropa y dise\u00f1os desde los ateliers de costura hasta las correcciones de Karl. Una mezcla de nervios y emociones.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00bfQu\u00e9 te apasiona del modelaje? <\/strong><\/p>\n<p>Fue algo que me pas\u00f3, una oportunidad que supe aprovechar pero no lo so\u00f1\u00e9. Hoy disfruto y me encanta mi trabajo, la gente tiene muy buena onda, viaj\u00e1s, conoc\u00e9s a muchas personas que vienen con sus historias, y te ayuda mucho a ser m\u00e1s abierto y sociable.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00bfQu\u00e9 tuviste que dejar por tu carrera?<\/strong><\/p>\n<p>Un mont\u00f3n de cosas, implica much\u00edsimos sacrificios pero b\u00e1sicamente el estar lejos de tu gente. Todo tipo de relaci\u00f3n es m\u00e1s complicada. Lo que m\u00e1s extra\u00f1o es estar lejos de tu familia los domingos, de las meriendas y salidas con amigas creo que es lo que m\u00e1s extra\u00f1o. Todo te hace crecer, tener que ser m\u00e1s sociable porque est\u00e1s viajando sola por el mundo.<strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>#YOELIJO<\/strong><\/p>\n<p><strong>Enamorada de:<\/strong> Viajar.<\/p>\n<p><strong>Qu\u00e9 lugar so\u00f1\u00e1s conocer:<\/strong> India, Kenya y Bali.<\/p>\n<p><strong>Un<\/strong> <strong>cocktail<\/strong>: Fernet, siempre.<\/p>\n<p><strong>Una<\/strong> <strong>frase<\/strong>: Amor por mi familia, no ser relativista y todo llega en la vida.<\/p>\n<p><strong>Un look de noche:<\/strong> Botas y vestidito negro o mini de cuero.<\/p>\n<p><strong>Un look de d\u00eda: <\/strong>Converse, jean grande o una mini y remera b\u00e1sica.<\/p>\n<p><strong>Un restaurant: <\/strong>Wild and the moon (Paris)<\/p>\n<p><strong>Un perfume: <\/strong>Good girl de Carolina Herrera<\/p>\n\r\n\t\t<style type='text\/css'>\r\n\t\t\t#gallery-1 {\r\n\t\t\t\tmargin: auto;\r\n\t\t\t}\r\n\t\t\t#gallery-1 .gallery-item {\r\n\t\t\t\tfloat: left;\r\n\t\t\t\tmargin-top: 10px;\r\n\t\t\t\ttext-align: center;\r\n\t\t\t\twidth: 33%;\r\n\t\t\t}\r\n\t\t\t#gallery-1 img {\r\n\t\t\t\tborder: 2px solid #cfcfcf;\r\n\t\t\t}\r\n\t\t\t#gallery-1 .gallery-caption {\r\n\t\t\t\tmargin-left: 0;\r\n\t\t\t}\r\n\t\t<\/style>\r\n\t\t<!-- see gallery_shortcode() in wp-includes\/media.php -->\n\t\t<div id='gallery-1' class='gallery galleryid-7740 gallery-columns-3 gallery-size-full gallery1'><script type=\"text\/javascript\">\r\n\/\/ <![CDATA[\r\n\tjQuery(document).ready(function () {\r\n\t\tjQuery(\".gallery1 a\").attr(\"rel\",\"gallery1\");\t\r\n\t\tjQuery('a[rel=\"gallery1\"]').colorbox({maxWidth:\"95%\", maxHeight:\"95%\",title: function(){ return jQuery(this).children().attr(\"alt\"); }, });\r\n\t});\r\n\/\/ ]]>\r\n<\/script>\n<dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/Ayres-SS19_4147-RGB-OK.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/Ayres-SS19_4147-RGB-OK.jpg\" width=\"895\" height=\"1343\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 895px; --smush-placeholder-aspect-ratio: 895\/1343;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/Ayres-SS19_3365-RGB-OK.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/Ayres-SS19_3365-RGB-OK.jpg\" width=\"922\" height=\"1382\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 922px; --smush-placeholder-aspect-ratio: 922\/1382;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/Ayres-SS19_2662-RGB-OK.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/Ayres-SS19_2662-RGB-OK.jpg\" width=\"895\" height=\"1343\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 895px; --smush-placeholder-aspect-ratio: 895\/1343;\" \/><\/a>\r\n<\/dt><\/dl><br style=\"clear: both\" \/>\r\n\t\t<\/div>\n\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00a0Mili es cordobesa, vive en Par\u00eds y es modelo de M\u00fanich Models. Arranc\u00f3 haciendo fotos planeando un intercambio en Par\u00eds. Fue modelo de grandes marcas como Chanel, Fendi y Levi\u00b4s. Conoc\u00e9 c\u00f3mo creci\u00f3 dentro del mundo fashion y todos los secretos en primera persona. \u00bfConociste a\u00a0Karl Lagerfeld?\u00a0 S\u00ed, lo conoc\u00ed primero en los fittings del [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":9481,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[30],"tags":[],"class_list":["post-7740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-moda"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/7740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=7740"}],"version-history":[{"count":0,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/7740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media\/9481"}],"wp:attachment":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=7740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=7740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=7740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}