{"id":71842,"date":"2023-10-04T15:14:47","date_gmt":"2023-10-04T18:14:47","guid":{"rendered":"https:\/\/www.lasrosas.com.ar\/portal\/?p=71842"},"modified":"2023-10-04T15:14:49","modified_gmt":"2023-10-04T18:14:49","slug":"paseo-del-jockey-celebro-la-primavera-con-un-festival-unico-sunset-parade-paseo-del-jockey-celebro-la-primavera-con-un-festival-unico-sunset-parade","status":"publish","type":"post","link":"https:\/\/www.lasrosas.com.ar\/portal\/paseo-del-jockey-celebro-la-primavera-con-un-festival-unico-sunset-parade-paseo-del-jockey-celebro-la-primavera-con-un-festival-unico-sunset-parade\/","title":{"rendered":"PASEO DEL JOCKEY CELEBR\u00d3 LA PRIMAVERA  CON UN FESTIVAL \u00daNICO: SUNSET PARADE PASEO DEL JOCKEY CELEBR\u00d3 LA PRIMAVERA  CON UN FESTIVAL \u00daNICO: SUNSET PARADE"},"content":{"rendered":"\n<p>El pasado s\u00e1bado 30, el centro comercial de la zona sur de nuestra ciudad vivi\u00f3 una aut\u00e9ntica fiesta para celebrar la primavera: el Sunset Parade del Paseo del Jockey.<\/p>\n\n\n\n<p>El festival, con entrada libre y gratuita, comenz\u00f3 a las 16 horas en la playa descubierta del shopping, y cont\u00f3 con una numerosa asistencia de m\u00e1s de 500 personas que disfrutaron de variadas y divertidas propuestas para toda la familia: juegos para grandes y chicos con importantes premios a cargo de marcas como Batistella, Nails&amp;Co, Lidherma, Tecno Compro, Chammas, Owoko, Rossetti, Talleres, Soleil bijouterie, Veterinaria Alem, Sweet Sweet Way, Fiorani, Eatwell, Bonafide y Mallorca Joyas. Tambi\u00e9n, foodtrucks con distintas propuestas gastron\u00f3micas como por ejemplo la de Turco Shawarma, Skallen Cerveza, Jalisco y Risata, m\u00fasica en vivo a cargo de Pricha con su fusi\u00f3n de gospel, blues y soul, y la DJ Greta Meier.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1281\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1544-1281x1920.jpg\" alt=\"\" data-id=\"71878\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1544-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71878\" class=\"wp-image-71878 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1544-1281x1920.jpg 1281w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1544-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1544-1025x1536.jpg 1025w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1544-scaled.jpg 1366w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/1920;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1280\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506671-1920x1280.jpg\" alt=\"\" data-id=\"71879\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506671-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71879\" class=\"wp-image-71879 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/\/J0506671-1920x1280.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/\/J0506671-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/\/J0506671-1536x1024.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/\/J0506671-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1280\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0586-1920x1280.jpg\" alt=\"\" data-id=\"71881\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0586-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71881\" class=\"wp-image-71881 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0586-1920x1280.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0586-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0586-1536x1024.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0586-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1280\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505559-1280x1920.jpg\" alt=\"\" data-id=\"71882\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505559-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71882\" class=\"wp-image-71882 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505559-1280x1920.jpg 1280w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505559-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505559-1024x1536.jpg 1024w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505559-scaled.jpg 1365w\" data-sizes=\"(max-width: 1280px) 100vw, 1280px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1280px; --smush-placeholder-aspect-ratio: 1280\/1920;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1280\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505614-1920x1280.jpg\" alt=\"\" data-id=\"71883\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505614-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71883\" class=\"wp-image-71883 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505614-1920x1280.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505614-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505614-1536x1024.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505614-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1280\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505979-1920x1280.jpg\" alt=\"\" data-id=\"71884\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505979-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71884\" class=\"wp-image-71884 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505979-1920x1280.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505979-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505979-1536x1024.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0505979-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1280\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506068-1920x1280.jpg\" alt=\"\" data-id=\"71885\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506068-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71885\" class=\"wp-image-71885 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506068-1920x1280.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506068-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506068-1536x1024.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506068-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1280\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506372-1280x1920.jpg\" alt=\"\" data-id=\"71886\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506372-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71886\" class=\"wp-image-71886 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506372-1280x1920.jpg 1280w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506372-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506372-1024x1536.jpg 1024w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506372-scaled.jpg 1365w\" data-sizes=\"(max-width: 1280px) 100vw, 1280px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1280px; --smush-placeholder-aspect-ratio: 1280\/1920;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1280\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506227-1920x1280.jpg\" alt=\"\" data-id=\"71887\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506227-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71887\" class=\"wp-image-71887 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506227-1920x1280.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506227-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506227-1536x1024.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/J0506227-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Luego, a las 19 hs, se llev\u00f3 a cabo un desfile de presentaci\u00f3n de la temporada primavera-verano \u201923 &#8211; \u201924, donde se mostraron las propuestas de algunas de sus marcas m\u00e1s relevantes como Wanama, Key Biscayne, Cero26, Malabia, Silenzio, Brooksfield, Marea, Legacy, Ver y Portsaid.<\/p>\n\n\n\n<p>Todas estas marcas desfilaron por la pasarela del Sunset Parade en un evento lleno de alegr\u00eda, m\u00fasica y color ante un p\u00fablico entusiasta entre el cual se encontraban relevantes personalidades de los medios y del mundo de la moda, adem\u00e1s de los clientes m\u00e1s fieles del Paseo.<\/p>\n\n\n\n<p>Luego del desfile, el festival cont\u00f3 con un broche de oro musical a cargo de la banda Vald\u00e9s que hizo gozar al p\u00fablico en lo que fue uno de sus \u00faltimos shows, ya que esta banda comunic\u00f3 que pr\u00f3ximamente se separar\u00e1.<\/p>\n\n\n\n<p><strong>Malabia<\/strong><\/p>\n\n\n\n<p>Flower Island es la nueva colecci\u00f3n SS24. Cada \u00edtem que la compone refleja c\u00f3mo lo aut\u00e9ntico y lo contempor\u00e1neo pueden coexistir en perfecta armon\u00eda. Sus colores vibrantes, textiles y estampas protagonistas nos conectan con la belleza de la naturaleza, de lo org\u00e1nico.<\/p>\n\n\n\n<p>En esta temporada c\u00e1lida, Flower Island permite fusionar el dinamismo del d\u00eda a d\u00eda con la frescura y genuinidad.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1281\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0617-1281x1920.jpg\" alt=\"\" data-id=\"71848\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0617-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71848\" class=\"wp-image-71848 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0617-1281x1920.jpg 1281w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0617-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0617-1025x1536.jpg 1025w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0617-scaled.jpg 1366w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/1920;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1281\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0675-1281x1920.jpg\" alt=\"\" data-id=\"71849\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0675-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71849\" class=\"wp-image-71849 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0675-1281x1920.jpg 1281w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0675-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0675-1025x1536.jpg 1025w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0675-scaled.jpg 1366w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/1920;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1281\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0679-1920x1281.jpg\" alt=\"\" data-id=\"71851\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0679-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71851\" class=\"wp-image-71851 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0679-1920x1281.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0679-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0679-1536x1025.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0679-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1281;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0689-1920x1920.jpg\" alt=\"\" data-id=\"71854\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0689-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71854\" class=\"wp-image-71854 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0689-1920x1920.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0689-960x960.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0689-1536x1536.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0689-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1920;\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><strong>Portsaid&nbsp;<\/strong><\/p>\n\n\n\n<p>Portsaid lanza su nueva colecci\u00f3n primavera-verano 2024 para vivir una nueva temporada llena de color e invitarte a sumergite en la alegr\u00eda de vivir la vida al m\u00e1ximo. Descubr\u00ed el poder de los colores, su energ\u00eda y reflej\u00e1 tu personalidad \u00fanica en cada tono y en cada prenda que integra la colecci\u00f3n.<\/p>\n\n\n\n<p>Inspiradas por los colores y texturas que nos ofrece la naturaleza, esta colecci\u00f3n de verano refleja la frescura del mar, la intensidad de un atardecer y la suavidad de la brisa marina.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1281\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1465-1920x1281.jpg\" alt=\"\" data-id=\"71850\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1465-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71850\" class=\"wp-image-71850 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1465-1920x1281.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1465-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1465-1536x1025.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1465-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1281;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1281\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1470-1920x1281.jpg\" alt=\"\" data-id=\"71853\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1470-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71853\" class=\"wp-image-71853 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1470-1920x1281.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1470-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1470-1536x1025.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1470-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1281;\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>No solo va a ser un look de verano, sino una forma de conectarse con el entorno.<\/p>\n\n\n\n<p>Desde los c\u00e1lidos amarillos que te abrazan con la calidez del sol, hasta los frescos azules que evocan la tranquilidad del mar, vas a encontrar una paleta de colores que celebra la diversidad y la autenticidad de todas las mujeres.<\/p>\n\n\n\n<p>Es verano, la estaci\u00f3n de la alegr\u00eda y la libertad. Color a pleno llega con tonos vibrantes, tejidos ligeros y dise\u00f1os para sentir un eterno d\u00eda de playa. Cada prenda se convertir\u00e1 en la aliada para expresar estilo y vivir el verano a pleno.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1280\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1397-1280x1920.jpg\" alt=\"\" data-id=\"71852\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1397-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71852\" class=\"wp-image-71852 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1397-1280x1920.jpg 1280w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1397-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1397-1024x1536.jpg 1024w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1397-scaled.jpg 1366w\" data-sizes=\"(max-width: 1280px) 100vw, 1280px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1280px; --smush-placeholder-aspect-ratio: 1280\/1920;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1281\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1445-1281x1920.jpg\" alt=\"\" data-id=\"71855\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1445-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71855\" class=\"wp-image-71855 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1445-1281x1920.jpg 1281w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1445-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1445-1025x1536.jpg 1025w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1445-scaled.jpg 1366w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/1920;\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><strong>Silenzio<\/strong><\/p>\n\n\n\n<p>En esta colecci\u00f3n, Silenzio transmite la esencia de la serenidad y la belleza natural del mar, la arena y su armon\u00eda. Fusiona el estilo de la mujer Silenzio con la vida de verano en diferentes situaciones, destacando un estilo relajado, chic y rom\u00e1ntico. Los colores protagonistas de las prendas de esta colecci\u00f3n son tonos c\u00e1lidos del atardecer, como el rosa, el naranja y los tonos del mar como el azul suave.<\/p>\n\n\n\n<p>Su nueva colecci\u00f3n se inspira en tres conceptos: Sensualidad veraniega, Soft utility y Carrera fluida.<\/p>\n\n\n\n<p>Sensualidad veraniega: en un estado de \u00e1nimo c\u00e1lido y edificante, y se conecta con el sentido de escapismo, uniendo la facilidad de la ropa de playa con la sofisticaci\u00f3n de la ropa moderna para ocasiones especiales. Sus elementos clave son vestidos fluidos, trajes de lino relajados, pantalones de pierna ancha, conjuntos \u201cCouch to coast\u201d y detalles de madera y n\u00e1car.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1281\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0943-1-1920x1281.jpg\" alt=\"\" data-id=\"71856\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0943-1-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71856\" class=\"wp-image-71856 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0943-1-1920x1281.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0943-1-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0943-1-1536x1025.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0943-1-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1281;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1280\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0919-1920x1280.jpg\" alt=\"\" data-id=\"71858\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0919-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71858\" class=\"wp-image-71858 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0919-1920x1280.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0919-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0919-1536x1024.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0919-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Soft Utility: contin\u00faa la necesidad de funcionalidad, longevidad y durabilidad. El utilitarismo se vuelve m\u00e1s soft, de la mano de las est\u00e9ticas de los 90s y los 00s, llevando looks m\u00e1s urbanos a ocasiones especiales y viceversa. Sus elementos clave son la falda midi, pantalones con bolsillos cargo, detalles ajustables y av\u00edos t\u00e9cnicos.<\/p>\n\n\n\n<p>Carrera flu\u00edda: Se inspira en la ropa de carrera profesional, volviendo a la elegancia de la sastrer\u00eda cl\u00e1sica de los 90s, pero con siluetas m\u00e1s fluidas y relajadas. Sus elementos clave son camisas a rayas, trajes sastre relajados, pantalones de pierna ancha, chalecos, blazers con solapa cruzada y denim.<\/p>\n\n\n\n<p>Las estampas giran en torno a elementos clave como rayas y motivos veraniegos, bot\u00e1nicos, vacacionales, paradis\u00edacos. Alegr\u00eda, optimismo, escapismo y colores vivos. Self-care, crecimiento personal, motivaci\u00f3n y refugio interior.<\/p>\n\n\n\n<p>El elemento clave de las estampas Full Print son los estampados lujosos en tonos c\u00e1lidos y gradientes digitales de color haciendo alusi\u00f3n a las #SunsetShades y #WaterColours.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1281\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0839-1281x1920.jpg\" alt=\"\" data-id=\"71857\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0839-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71857\" class=\"wp-image-71857 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0839-1281x1920.jpg 1281w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0839-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0839-1024x1536.jpg 1024w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0839-scaled.jpg 1366w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/1920;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1281\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0891-1281x1920.jpg\" alt=\"\" data-id=\"71859\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0891-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71859\" class=\"wp-image-71859 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0891-1281x1920.jpg 1281w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0891-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0891-1025x1536.jpg 1025w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0891-scaled.jpg 1366w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/1920;\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><strong>Ver<\/strong><\/p>\n\n\n\n<p>El concepto de esta colecci\u00f3n es Piedra Libre, que es una forma de decir libertad, es volver a la ni\u00f1a interior, a la potencia de jugar.<\/p>\n\n\n\n<p>Una excusa para liberarse de los mandatos, poner sobre la mesa la flexibilidad de la moda y volver a s\u00ed mismas.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1281\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1294-1281x1920.jpg\" alt=\"\" data-id=\"71861\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1294-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71861\" class=\"wp-image-71861 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1294-1281x1920.jpg 1281w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1294-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1294-1025x1536.jpg 1025w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1294-scaled.jpg 1366w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/1920;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1281\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1310-1281x1920.jpg\" alt=\"\" data-id=\"71862\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1310-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71862\" class=\"wp-image-71862 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1310-1281x1920.jpg 1281w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1310-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1310-1025x1536.jpg 1025w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1310-scaled.jpg 1366w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/1920;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1281\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1347-1920x1281.jpg\" alt=\"\" data-id=\"71863\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1347-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71863\" class=\"wp-image-71863 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1347-1920x1281.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1347-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1347-1536x1025.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1347-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1281;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1281\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1363-1920x1281.jpg\" alt=\"\" data-id=\"71864\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1363-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71864\" class=\"wp-image-71864 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1363-1920x1281.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1363-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1363-1536x1025.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1363-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1281;\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>La Piedra Libre que dice que pod\u00e9s ponerte lo que quieras, cuando quieras, si te hace sentir bien a vos. \u00bfPiedra Libre para qui\u00e9n? \u00bfPor qu\u00e9? \u00bfC\u00f3mo?<\/p>\n\n\n\n<p>Piedra Libre para todas seg\u00fan sus b\u00fasquedas, sus deseos, y sus miradas del mundo.<\/p>\n\n\n\n<p><strong>Wanama<\/strong><\/p>\n\n\n\n<p>Wanama, la marca que celebra la libertad y la autenticidad, se inspira en la naturaleza para dar vida a su \u00faltima colecci\u00f3n, \u00abFreedom Chasers\u00bb. Con un compromiso inquebrantable de crear prendas atemporales, cl\u00e1sicas y duraderas, Wanama fusiona detalles excepcionales y tejidos nobles que cuentan historias propias.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1281\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0390-1281x1920.jpg\" alt=\"\" data-id=\"71865\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0390-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71865\" class=\"wp-image-71865 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0390-1281x1920.jpg 1281w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0390-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0390-1024x1536.jpg 1024w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0390-scaled.jpg 1366w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/1920;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1281\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0424-1920x1281.jpg\" alt=\"\" data-id=\"71866\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0424-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71866\" class=\"wp-image-71866 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0424-1920x1281.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0424-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0424-1536x1025.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0424-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1281;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1281\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0450-1281x1920.jpg\" alt=\"\" data-id=\"71867\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0450-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71867\" class=\"wp-image-71867 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0450-1281x1920.jpg 1281w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0450-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0450-1025x1536.jpg 1025w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0450-scaled.jpg 1366w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/1920;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1281\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0477-1920x1281.jpg\" alt=\"\" data-id=\"71868\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0477-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71868\" class=\"wp-image-71868 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0477-1920x1281.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0477-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0477-1536x1024.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0477-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1281;\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>La filosof\u00eda de Wanama se refleja en un \u00abtotal look\u00bb, donde cada prenda se complementa a la perfecci\u00f3n. Adem\u00e1s, la colecci\u00f3n se enriquece con una selecci\u00f3n de accesorios, incluyendo bolsos, calzado y gafas, dise\u00f1ados para adaptarse a diversas situaciones con estilo y elegancia.<\/p>\n\n\n\n<p>La esencia de la naturaleza se encuentra en el coraz\u00f3n de \u00abFreedom Chasers\u00bb, con estampados inspirados en la belleza natural que dominan y definen la colecci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Este verano estar\u00e1 lleno de colores vibrantes y la sensaci\u00f3n de libertad que solo Wanama puede ofrecer.<\/p>\n\n\n\n<p><strong>Legacy<\/strong><\/p>\n\n\n\n<p>Legacy presenta Legacy Paradise Club. Esta temporada el disfrutar del verano en la naturaleza selv\u00e1tica, el mar azul y las arenas blancas de Playa del Carmen, inspiran nuestra colecci\u00f3n y paleta crom\u00e1tica.<\/p>\n\n\n\n<p>Desde los tonos m\u00e1s brillantes y saturados, llenos de vida y energ\u00eda, hasta los m\u00e1s pasteles y terrosos, est\u00e1n presentes en las diferentes prendas. El enfoque de la colecci\u00f3n se centra en la b\u00fasqueda de equilibrio, armon\u00eda y renovaci\u00f3n, expresando las emociones con optimismo.<\/p>\n\n\n\n<p>La paleta est\u00e1 integrada por tonalidades c\u00e1lidas como rojo y amarillo solar, colores florales como lila y rosa suave y naranjas c\u00edtricos.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-9 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1281\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1251-1920x1281.jpg\" alt=\"\" data-id=\"71869\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1251-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71869\" class=\"wp-image-71869 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1251-1920x1281.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1251-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1251-1536x1024.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1251-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1281;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1280\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A1076-1920x1280.jpg\" alt=\"\" data-id=\"71871\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A1076-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71871\" class=\"wp-image-71871 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A1076-1920x1280.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A1076-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A1076-1536x1024.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A1076-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>En la gama de los verdes, los m\u00e1s destacados son el olive green y el esmeralda, el primero natural y fresco y el segundo brillante y saturado, pero tambi\u00e9n los acompa\u00f1a el aqua baby, un verde suave y ex\u00f3tico.<\/p>\n\n\n\n<p>La paleta de los azules comienza con los celestes limpios y puros, sigue con los aeros luminosos y los francias el\u00e9ctricos y finaliza con el marino, calmo y relajado.<\/p>\n\n\n\n<p>El marr\u00f3n de la madera y de los granos de caf\u00e9, junto con los tierras, se transforman en los nuevos neutros, tonos seguros y confiables que se combinan con colores pasteles o brillantes renovando nuestros looks cl\u00e1sicos.<\/p>\n\n\n\n<p>Pero el blanco, los beiges, el vainilla cremoso, los grises y el negro no desaparecieron, siguen presente en la temporada aportando sobriedad y atemporalidad.<\/p>\n\n\n\n<p>En la colecci\u00f3n de hombre y mujer proponemos conjuntos que buscan combinar lo cl\u00e1sico y tradicional con lo relajado e informal, priorizando el confort. Utilizamos telas frescas y ligeras como lino y algod\u00f3n e incorporamos buzos y sweaters amplios con rayas n\u00e1uticas, aranes y calados ideales para un atardecer de verano.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-10 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1281\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1193-1281x1920.jpg\" alt=\"\" data-id=\"71870\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1193-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71870\" class=\"wp-image-71870 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1193-1281x1920.jpg 1281w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1193-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1193-1024x1536.jpg 1024w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1193-scaled.jpg 1366w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/1920;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1281\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1238-1281x1920.jpg\" alt=\"\" data-id=\"71872\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1238-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71872\" class=\"wp-image-71872 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1238-1281x1920.jpg 1281w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1238-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1238-1025x1536.jpg 1025w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A1238-scaled.jpg 1366w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/1920;\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><strong>Cero26<\/strong><\/p>\n\n\n\n<p>CHAMPION propone prendas para aventureros, confiados y divertidos, que combinan la expresi\u00f3n ligera de una marca de estilo urbano, con el enfoque determinado de una marca deportiva, para expresarse con confianza, libertad y sentirse bien..<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-11 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1920\" height=\"1280\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0881-1920x1280.jpg\" alt=\"\" data-id=\"71875\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0881-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71875\" class=\"wp-image-71875 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0881-1920x1280.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0881-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0881-1536x1024.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/123A0881-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1281\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0768-1-1281x1920.jpg\" alt=\"\" data-id=\"71877\" data-full-url=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0768-1-scaled.jpg\" data-link=\"https:\/\/www.lasrosas.com.ar\/portal\/?attachment_id=71877\" class=\"wp-image-71877 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0768-1-1281x1920.jpg 1281w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0768-1-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0768-1-1025x1536.jpg 1025w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0768-1-scaled.jpg 1366w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/1920;\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>QUICKSILVER, la compa\u00f1\u00eda m\u00e1s importante del mundo de los deportes de deslizamiento abri\u00f3 su mercado no s\u00f3lo a la ropa y material t\u00e9cnico para el surf, skate o snowboard y todo tipo de accesorios sino a nuevos nichos para convertirse en un referente en cuanto a moda y calidad<\/p>\n\n\n\n<p>ROXY representa una nueva generaci\u00f3n de atletas, j\u00f3venes, salvajes y libres.<\/p>\n\n\n\n<p>Es una marca de deportes que va en contra de la corriente de la moda para mujeres. Roxy se trata de cuidarse por dentro y por fuera, creando una colecci\u00f3n de ropa deportiva para lucir bien al hacer ejercicio.<\/p>\n\n\n\n<p>FILA present\u00f3 \u201cChange The Future\u201d celebra la relaci\u00f3n que FILA tiene con el futuro del planeta sin perder la conexi\u00f3n con el estilo.&nbsp;<\/p>\n\n\n\n<p>Para esta temporada, FILA trae opciones para quienes buscan piezas que aporten mucho m\u00e1s que estilo. Change The Future ofrece una colecci\u00f3n de indumentaria y zapatillas que utiliza materiales sustentables y restos de materiales de la producci\u00f3n de miles de otros modelos de la marca.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1281\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0768-1281x1920.jpg\" alt=\"\" class=\"wp-image-71876 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0768-1281x1920.jpg 1281w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0768-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0768-1025x1536.jpg 1025w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0768-scaled.jpg 1366w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/1920;\" \/><\/figure>\n\n\n\n<p>Con una paleta cool y modelos c\u00f3modos que se pueden usar en diferentes estaciones del a\u00f1o, toda la l\u00ednea de indumentaria fue dise\u00f1ada para ser unisex, simplificar la producci\u00f3n y expresar la actitud Change the future de una manera sencilla y sin esfuerzo. La misma incluye camisetas, pantalones, bermudas, shorts y hoodies con capucha realizados en&nbsp; algod\u00f3n y poli\u00e9ster reciclados en algunas prendas, y confeccionado con hilos de coser, tejidos y estampados sostenibles en toda la colecci\u00f3n. Destacan las prendas oversize y c\u00f3modas en tonos rosas, con estampas exclusivas de la c\u00e1psula.<\/p>\n\n\n\n<p>La l\u00ednea de calzados Green Pack acompa\u00f1a la colecci\u00f3n para completar un look aut\u00e9ntico y garantizar originalidad con el m\u00e1ximo confort. Desarrolladas parcialmente con materiales reciclados, las nuevas ACD Mid y Arcade Low conforman esta iniciativa sustentable y con estilo creada por FILA. Priorizando la producci\u00f3n con menos desperdicio, la marca utiliz\u00f3 su ingenier\u00eda de desarrollo de productos para unir eficiencia y reutilizaci\u00f3n de restos de la producci\u00f3n de otros modelos para recrear zapatillas aut\u00e9nticas con menor impacto en el medio ambiente.<\/p>\n\n\n\n<p>El Green Pack fue desarrollado para consumidores exigentes que buscan innovaci\u00f3n, estilo atemporal y siluetas con una visi\u00f3n que anticipa un futuro m\u00e1s sostenible. Ambos cuentan con una puntera producida con la reutilizaci\u00f3n de hilos String sobrantes del proceso de producci\u00f3n de calzado, cordones y forro hechos con hilos de PET reciclado y una suela de caucho compuesta en un 30% de regrind.<\/p>\n\n\n\n<p>LACOSTE \u2013 NETFLIX: en el crossover m\u00e1s esperado del a\u00f1o, el cocodrilo se sumerge en las series favoritas con la nueva colecci\u00f3n Lacoste x Netflix. Prendas exclusivas inspiradas en los shows preferidos.<\/p>\n\n\n\n<p>Es el punto de partida de la celebraci\u00f3n de los 90 a\u00f1os de Lacoste. Los universos de los personajes de ficci\u00f3n se suman en ella al vestuario sportswear chic de Lacoste.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1281\" height=\"1920\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0776-1281x1920.jpg\" alt=\"\" class=\"wp-image-71873 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0776-1281x1920.jpg 1281w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0776-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0776-1025x1536.jpg 1025w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0776-scaled.jpg 1366w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/1920;\" \/><\/figure>\n\n\n\n<p>La colecci\u00f3n se inspira en ocho series emblem\u00e1ticas de Netflix: Stranger Things, Lupin, Sex Education, Shadow &amp; Bone, \u00c9lite, La Casa de Papel, The Witcher y Bridgerton. Para esta \u00faltima, el Cocodrilo se transforma en monarca y luce una peluca de gran tama\u00f1o en un entorno suntuoso y brit\u00e1nico, que evoca la Inglaterra del S. XIX<em>.<\/em><\/p>\n\n\n\n<p>ADIDAS-&nbsp; ADICOLOR narra la historia de las tres ic\u00f3nicas rayas, buscando inmortalizar su legado mediante la incorporaci\u00f3n de los logotipos del tr\u00e9bol en las sudaderas, camisetas y ch\u00e1ndales de esta colecci\u00f3n. Esta l\u00ednea nos transporta de vuelta a los vibrantes a\u00f1os 70, canalizando los colores y dise\u00f1os de esa \u00e9poca de una manera que fusiona lo retro con lo moderno.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1920\" height=\"1281\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0822-1920x1281.jpg\" alt=\"\" class=\"wp-image-71874 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0822-1920x1281.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0822-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0822-1536x1024.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/1A5A0822-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1281;\" \/><\/figure>\n\n\n\n<p>Desde pantalones hasta camperas, buzos y m\u00e1s, esta colecci\u00f3n lleva el inconfundible sello de calidad y comodidad de Adidas: un look que captura la esencia de la nostalgia, pero con un toque de contemporaneidad.<br><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El pasado s\u00e1bado 30, el centro comercial de la zona sur de nuestra ciudad vivi\u00f3 una aut\u00e9ntica fiesta para celebrar la primavera: el Sunset Parade del Paseo del Jockey. El festival, con entrada libre y gratuita, comenz\u00f3 a las 16 horas en la playa descubierta del shopping, y cont\u00f3 con una numerosa asistencia de m\u00e1s [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":71880,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[234,100,30],"tags":[],"class_list":["post-71842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trend","category-noticias","category-moda"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/71842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=71842"}],"version-history":[{"count":3,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/71842\/revisions"}],"predecessor-version":[{"id":71888,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/71842\/revisions\/71888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media\/71880"}],"wp:attachment":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=71842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=71842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=71842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}