{"id":70131,"date":"2023-08-24T14:00:04","date_gmt":"2023-08-24T17:00:04","guid":{"rendered":"https:\/\/www.lasrosas.com.ar\/portal\/?p=70131"},"modified":"2023-08-24T14:00:08","modified_gmt":"2023-08-24T17:00:08","slug":"entrevista-a-cecilia-alvarez","status":"publish","type":"post","link":"https:\/\/www.lasrosas.com.ar\/portal\/entrevista-a-cecilia-alvarez\/","title":{"rendered":"ENTREVISTA A CECILIA ALVAREZ"},"content":{"rendered":"\n<p><strong>\u00bfC\u00f3mo te convertiste en una artista de u\u00f1as?<\/strong><\/p>\n\n\n\n<p>Comenc\u00e9 en este mundo despu\u00e9s de haber ganado un concurso de belleza en el que me coronaron Reina de mi Localidad, luego de eso comenc\u00e9 mi carrera como como modelo, lo cual requer\u00eda que siempre tenga las u\u00f1as lindas y prolijas para los desfiles o las fotos de campanas.<br>La manicura que me hac\u00eda las u\u00f1as se mud\u00f3 super lejos y como me hac\u00eda seguido el servicio cre\u00eda que ya sab\u00eda todo lo necesario, claramente estaba equivocada. Me compre todos los productos y dije, esto debe ser f\u00e1cil pero no fue as\u00ed, mi primer set de u\u00f1as me llev\u00f3 10 horas y el resultado no fue el esperado pero por ser mi primera vez no hab\u00edan quedado tan mal. tal es as\u00ed que segu\u00ed haciendo mis u\u00f1as y las de mis amigas, lo cual me encantaba.<br>Hab\u00eda encontrado un hobby, una pasi\u00f3n, un lugar de creatividad, un espacio social, pero lo que m\u00e1s me enamoraba de esto era ver la cara de felicidad de las personas que atendi\u00f3 cuando ve\u00edan el resultado final.<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1l es el secreto de una artista nail?<\/strong><\/p>\n\n\n\n<p>Mi secreto es ser aplicada y disciplinada, capacitarme constantemente con las nuevas t\u00e9cnicas, productos y tendencias. Lo m\u00e1s importante para mi fue practicar mucho. Es crucial no perder el entusiasmo cuando los servicios no salen como me gustar\u00eda. Soy muy exigente conmigo c\u00f3mo nails artista.<\/p>\n\n\n\n<p><strong>Las u\u00f1as se han vuelto un foco importante en la moda de los \u00faltimos a\u00f1os \u00bfPor qu\u00e9 surge este inter\u00e9s?<\/strong><br>En Argentina el boom de las u\u00f1as explot\u00f3 en los \u00faltimos 5 a\u00f1os y su pico fue la pandemia, todas las redes sociales se inundaron de unas hermosas y perfectas, esto hizo que sea un servicio de belleza irresistible para todas las mujeres.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1920\" height=\"1280\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC01795-1920x1280.jpg\" alt=\"\" class=\"wp-image-70221 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC01795-1920x1280.jpg 1920w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC01795-960x640.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC01795-1536x1024.jpg 1536w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC01795-scaled.jpg 2048w\" data-sizes=\"(max-width: 1920px) 100vw, 1920px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/figure>\n\n\n\n<p><strong>\u00bfC\u00f3mo fundaste Paloma nails boutique? \u00bfC\u00f3mo fue el proceso, cu\u00e1ntos locales tienes actualmente?<\/strong><\/p>\n\n\n\n<p>Mi reconocimiento como nails artista me permiti\u00f3 fundar en el a\u00f1o 2018 mi propia empresa de belleza llamada Paloma Nails Boutique. Tenia el sue\u00f1o de tener un espacio donde pudiera hacer lo que m\u00e1s amaba y tambi\u00e9n poder ense\u00f1ar a m\u00e1s mujeres este hermoso oficio.<br>Estaba tan entusiasmada con la gran aceptaci\u00f3n de los clientes tanto para atenderse conmigo o con mis alumnas que el lugar siempre estaba lleno, no brind\u00e1bamos citas y atend\u00edamos por orden de llegada, hab\u00eda fila de personas afuera de los salones esperando para atenderse. Quise abrir salones en las zonas linderas para descomprimir el primer sal\u00f3n.<br>Actualmente estamos listos para hacer la expansi\u00f3n en todo el territorio Argentino, tenemos varios salones abiertos y en los pr\u00f3ximos meses tenemos aperturas programadas en las zonas &nbsp;m\u00e1s exclusivas de Buenos Aires.<\/p>\n\n\n\n<p><strong>\u00bfCon qu\u00e9 celebrities argentinas trabajaste?<\/strong>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n\n\n\n<p>Mi reputaci\u00f3n como nails artista me brindo la posibilidad de Hacer mi trabajo &nbsp;a Eva De Dominici, Steff Roitman, Rocio Guirao Diaz, Julieta Bartolome, Laura Novoa, Monica Ayos, Anibal Pachano, Flavio Mendoza, Claudia Albertario, Laura Fidalgo, Charlotte Caniggia, Florencia Vigna, Mirtha Wons, Karina \u201cLa Princesita\u201d, Facundo Mazzei, Micaela Lapegue, etc.<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1les crees que ser\u00e1n las pr\u00f3ximas tendencias en u\u00f1as?<\/strong><\/p>\n\n\n\n<p>Las revistas de moda nos dicen que las tendencias que se vienen son los colores: amarillo delicado, rosa en todas sus versiones, rojo tomato cherry, color plata, morado y lila. Los efectos m\u00e1s pedidos en unas ser\u00e1n el aurora y el cromo.&nbsp;<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 ofrece tu sal\u00f3n que no ofrecen otros?<\/strong><\/p>\n\n\n\n<p>Puedo hablarte de lo que ofrezco yo como nails artista y que es lo mismo que les ense\u00f1\u00f3 a las manicuras que trabajan en nuestros salones y a las alumnas de nuestra mi escuela. Pasi\u00f3n, dedicaci\u00f3n, Calidad en el servicio, profesionalismo y una excelente atenci\u00f3n al cliente.<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1l es tu secreto para tener las u\u00f1as lindas y bien cuidadas?<\/strong><br>mi secreto es ser atendida por mis colegas recibidas en mi escuela, siempre pido mis u\u00f1as cortas y redondas, lo cual me deja desarrollarme como nails artista c\u00f3modamente.&nbsp;<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 eventos son los m\u00e1s importantes que trabajaste como nails artista?<\/strong><\/p>\n\n\n\n<p>Trabaje haciendo unas en varias obras de teatros de Flavio Mendoza y a \u00e9l en muchas oportunidades, tambi\u00e9n &nbsp;haciendo las u\u00f1as del jurado en el programa de Marcelo Tinelli \u201cShow Match\u201d, a Laura Fidalgo y Anibal Pachano, tambi\u00e9n atend\u00ed a cantantes para sus conciertos o videoclip Karina \u201cla princesita\u201d, Facundo Mazzei, Florencia Vigna. Prepare las u\u00f1as a la periodista Melisa Zurita para su programa en canal 26. Organice eventos de Belleza masivos en hoteles para m\u00e1s de 100 manicuras y estuve presente en la exposici\u00f3n de unas m\u00e1s grande de nuestro pa\u00eds \u201cexpo de u\u00f1as y make up\u201d, c\u00f3mo nails artista invitada. Monte el stand m\u00e1s grande de la \u201cexposici\u00f3n de unas y make up\u201d en el predio de la Rural con atenci\u00f3n al cliente y brinde cursos y talleres gratuitos para todas las manicuras presentes. En nuestra escuela se reciben m\u00e1s de 1200 alumnas anuales lo cual me da mucho reconocimiento entre&nbsp;mis&nbsp;colegas. <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo te convertiste en una artista de u\u00f1as? Comenc\u00e9 en este mundo despu\u00e9s de haber ganado un concurso de belleza en el que me coronaron Reina de mi Localidad, luego de eso comenc\u00e9 mi carrera como como modelo, lo cual requer\u00eda que siempre tenga las u\u00f1as lindas y prolijas para los desfiles o las fotos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":70222,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[376,100,38],"tags":[],"class_list":["post-70131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lifestyle","category-noticias","category-entrevistas"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/70131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=70131"}],"version-history":[{"count":0,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/70131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media\/70222"}],"wp:attachment":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=70131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=70131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=70131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}