{"id":64757,"date":"2023-03-29T13:51:39","date_gmt":"2023-03-29T16:51:39","guid":{"rendered":"https:\/\/www.lasrosas.com.ar\/portal\/?p=64757"},"modified":"2023-03-29T13:51:42","modified_gmt":"2023-03-29T16:51:42","slug":"euforia-por-el-regreso-de-los-red-hot-chili-peppers-agotan-dos-estadios-river-en-tiempo-record","status":"publish","type":"post","link":"https:\/\/www.lasrosas.com.ar\/portal\/euforia-por-el-regreso-de-los-red-hot-chili-peppers-agotan-dos-estadios-river-en-tiempo-record\/","title":{"rendered":"EUFORIA POR EL REGRESO DE LOS RED HOT CHILI PEPPERS: AGOTAN DOS ESTADIOS RIVER EN TIEMPO R\u00c9CORD"},"content":{"rendered":"\n<p>CIENTOS DE MILES DE FANS HICIERON FILA EN\nLA PLATAFORMA DESDE MUY TEMPRANO Y COMPRARON TODOS LOS TICKETS DE LA NUEVA\nFECHA EN RIVER PLATE EN SOLO DOS HORAS<\/p>\n\n\n\n<p>La ic\u00f3nica banda vendr\u00e1 con su formaci\u00f3n\nm\u00e1s cl\u00e1sica, integrada por Anthony Kiedis, Flea, Chad Smith y el eximio\nguitarrista John Frusciante, que volvi\u00f3 a sumarse despu\u00e9s de 10 a\u00f1os, para\nbrindar dos presentaciones en Argentina los d\u00edas 24 y 26 de noviembre en el\nEstadio River Plate.<\/p>\n\n\n\n<p>La trascendencia de los Red Hot Chili\nPeppers es tal que, al anunciar su regreso a Argentina con un show en el\nEstadio River Plate presentado por Flow para el 24 de noviembre, era de esperar\nque se encendiera la chispa del furor de sus fans argentinos. La ic\u00f3nica banda\ncaliforniana vuelve despu\u00e9s de 5 a\u00f1os, con dos discos reci\u00e9n estrenados, su\nformaci\u00f3n m\u00e1s emblem\u00e1tica, y celebrando nada menos que su 40 aniversario. Tras\nhaber agotado las localidades para esa presentaci\u00f3n en tiempo r\u00e9cord, los Red\nHot hicieron realidad el sue\u00f1o de la multitud de fans que se hab\u00eda quedado afuera\ny confirmaron su nuevo show en Argentina para el domingo 26 de noviembre.\nCientos de miles de fan\u00e1ticos hicieron la fila virtual desde muy temprano hasta\nque llegaron las 10 am, cuando la desesperaci\u00f3n por conseguir entradas hizo que\nen tan s\u00f3lo dos horas no quedaran m\u00e1s tickets. Con estos dos sold-out \u00e9picos,\nqueda demostrada la contundente respuesta de los amantes de los Red Hot Chili\nPeppers en Argentina, que disfrutar\u00e1n de dos shows colmados en River Plate y\nvivir\u00e1n una verdadera fiesta junto a la banda de sus vidas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1080\" height=\"1350\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/unnamed-1-28.png\" alt=\"\" class=\"wp-image-64758 lazyload\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/unnamed-1-28.png 1080w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/unnamed-1-28-768x960.png 768w\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1350;\" \/><\/figure>\n\n\n\n<p>Tras la\nreincorporaci\u00f3n del venerado guitarrista John Frusciante en 2019 luego de 10\na\u00f1os de ausencia de la banda, en 2022 vieron la luz dos \u00e1lbumes nuevos con el\nmaterial de sus sesiones en el estudio: Unlimited Love y Return of the Dream\nCanteen. A fines de 2022 anunciaron una gira mundial con su formaci\u00f3n m\u00e1s\nhitera, confirmando fechas por Norteam\u00e9rica y Europa para presentar las\ncanciones nuevas as\u00ed como para festejar nada menos que su aniversario n\u00famero\n40. Los rumores por la etapa sudamericana del tour no pararon de crecer desde\nnoviembre del a\u00f1o pasado, cuando se viraliz\u00f3 un video del baterista de la\nbanda, Chad Smith, asegur\u00e1ndole a un fan argentino que volver\u00edan a tocar en el\npa\u00eds en el 2023. Las fechas anunciadas a comienzos de marzo en Brasil reavivaron\nel sue\u00f1o que ahora se convierte en realidad.<\/p>\n\n\n\n<p>Desde 1993,\ncuando hicieron su debut en vivo en el pa\u00eds, la banda vino en siete ocasiones,\nmientras su p\u00fablico fiel crec\u00eda en n\u00fameros y se sumaban nuevas generaciones de\nfans. La \u00faltima vez fue en el a\u00f1o 2017, cuando cerraron el festival\nLollapalooza. El show en River promete ser la oportunidad para reencontrarse\ncon los Red Hot y ser parte del cruce entre la adrenalina de sus estrenos y el\npaso obligado por los cl\u00e1sicos, enlazados a recuerdos de diferentes etapas en\nla vida de sus miles de fans. El fen\u00f3meno r\u00e9cord ante su esperada vuelta no\nhace m\u00e1s que confirmar que la banda est\u00e1 m\u00e1s vigente que nunca y que sus\nseguidores argentinos \u2013y de toda la regi\u00f3n\u2013 son cada vez m\u00e1s.<\/p>\n\n\n\n<p>TICKETS\nOFICIALES \u00daNICAMENTE<\/p>\n\n\n\n<p>EN\nWWW.ALLACCESS.COM.AR<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>CIENTOS DE MILES DE FANS HICIERON FILA EN LA PLATAFORMA DESDE MUY TEMPRANO Y COMPRARON TODOS LOS TICKETS DE LA NUEVA FECHA EN RIVER PLATE EN SOLO DOS HORAS La ic\u00f3nica banda vendr\u00e1 con su formaci\u00f3n m\u00e1s cl\u00e1sica, integrada por Anthony Kiedis, Flea, Chad Smith y el eximio guitarrista John Frusciante, que volvi\u00f3 a sumarse [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":64759,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-64757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/64757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=64757"}],"version-history":[{"count":0,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/64757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media\/64759"}],"wp:attachment":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=64757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=64757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=64757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}