{"id":57764,"date":"2022-10-04T16:53:05","date_gmt":"2022-10-04T19:53:05","guid":{"rendered":"https:\/\/www.lasrosas.com.ar\/portal\/?p=57764"},"modified":"2022-10-04T16:53:05","modified_gmt":"2022-10-04T19:53:05","slug":"victorias-secret-presento-su-nueva-campana","status":"publish","type":"post","link":"https:\/\/www.lasrosas.com.ar\/portal\/victorias-secret-presento-su-nueva-campana\/","title":{"rendered":"VICTORIA\u2019S SECRET PRESENT\u00d3 SU NUEVA CAMPA\u00d1A"},"content":{"rendered":"<p>La compa\u00f1\u00eda de lencer\u00eda sigue apostando por una nueva imagen y hoy se anima a celebrar a todo tipo de mujeres, alej\u00e1ndose de la perfecci\u00f3n que impuso por d\u00e9cadas.<\/p>\n<p>Durante los \u00faltimos a\u00f1os Victoria\u00b4s Secret (VS) sufri\u00f3 muchos cambios. Es que la gente se cans\u00f3 de sus \u00e1ngeles, de sus desfiles y del mensaje que enviaban con ellos, quer\u00edan ver mujeres reales. Y la verdad, es que resistieron todo lo que pudieron hasta que las ventas tocaron niveles m\u00ednimos hist\u00f3ricos que los hizo entender que era cambiar o desaparecer. Y as\u00ed lo hicieron, hoy presentaron \u00abUndefinable\u00bb su nueva campa\u00f1a de la que participan todo tipos de mujeres.<\/p>\n<p>Un compromiso continuo<\/p>\n<p>Si bien hay muchos que acusan a la firma de lencer\u00eda de que su repentino cambio es solo una estrategia de marketing, desde VS aseguran de que es un compromiso continuo que se han tomado y que va m\u00e1s all\u00e1 de una colecci\u00f3n espec\u00edfica. \u00abQueremos celebrar a las mujeres, no estamos ac\u00e1 para dictar ni definir la belleza de nadie. Celebramos las individualidades\u00bb dijo Ra\u00fal Mart\u00ednez, vicepresidente ejecutivo y director creativo de VS en la presentaci\u00f3n de la campa\u00f1a.<\/p>\n\r\n\t\t<style type='text\/css'>\r\n\t\t\t#gallery-1 {\r\n\t\t\t\tmargin: auto;\r\n\t\t\t}\r\n\t\t\t#gallery-1 .gallery-item {\r\n\t\t\t\tfloat: left;\r\n\t\t\t\tmargin-top: 10px;\r\n\t\t\t\ttext-align: center;\r\n\t\t\t\twidth: 33%;\r\n\t\t\t}\r\n\t\t\t#gallery-1 img {\r\n\t\t\t\tborder: 2px solid #cfcfcf;\r\n\t\t\t}\r\n\t\t\t#gallery-1 .gallery-caption {\r\n\t\t\t\tmargin-left: 0;\r\n\t\t\t}\r\n\t\t<\/style>\r\n\t\t<!-- see gallery_shortcode() in wp-includes\/media.php -->\n\t\t<div id='gallery-1' class='gallery galleryid-57764 gallery-columns-3 gallery-size-full gallery1'><script type=\"text\/javascript\">\r\n\/\/ <![CDATA[\r\n\tjQuery(document).ready(function () {\r\n\t\tjQuery(\".gallery1 a\").attr(\"rel\",\"gallery1\");\t\r\n\t\tjQuery('a[rel=\"gallery1\"]').colorbox({maxWidth:\"95%\", maxHeight:\"95%\",title: function(){ return jQuery(this).children().attr(\"alt\"); }, });\r\n\t});\r\n\/\/ ]]>\r\n<\/script>\n<dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-10-04-at-4.51.36-PM-6.jpeg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-10-04-at-4.51.36-PM-6.jpeg\" width=\"740\" height=\"886\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 740px; --smush-placeholder-aspect-ratio: 740\/886;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-10-04-at-4.51.36-PM-5.jpeg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-10-04-at-4.51.36-PM-5.jpeg\" width=\"740\" height=\"908\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 740px; --smush-placeholder-aspect-ratio: 740\/908;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-10-04-at-4.51.36-PM-4.jpeg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-10-04-at-4.51.36-PM-4.jpeg\" width=\"740\" height=\"885\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 740px; --smush-placeholder-aspect-ratio: 740\/885;\" \/><\/a>\r\n<\/dt><\/dl><br style=\"clear: both\" \/>\r\n\t\t<\/div>\n\n<p>Celebrando las individualidades<\/p>\n<p>Una modelo, una activista, una atleta paral\u00edmpica, una luchadora, cada una de las mujeres de estas fotos cuenta una historia diferente. VS se aleja de la delgadez extrema, de las medidas perfectas y hoy apuesta a otra cosa. La firma asegura que est\u00e1 feliz de poder contar y mostrar realidades diferentes de mujeres que se destacan en diferentes formas.<\/p>\n<p>Documental pol\u00e9mico<\/p>\n<p>Hace meses se estren\u00f3 un documental que revela internas de VS, su relaci\u00f3n con Jeffrey Espstein, las conductas indebidas de Ed Razek (director de la firma) y las incre\u00edbles dietas a las que se somet\u00edan las modelos para caminar por la pasarela de su m\u00edtico desfile. Adriana Lima confes\u00f3 que estaba casi deshidratada para \u00ablucir perfecta\u00bb durante el show. Ser un \u00e1ngel de Victoria\u00b4s Secret era el sue\u00f1o de muchas, pero para otras fue una pesadilla. Y as\u00ed lo revela este documental.<\/p>\n\r\n\t\t<style type='text\/css'>\r\n\t\t\t#gallery-2 {\r\n\t\t\t\tmargin: auto;\r\n\t\t\t}\r\n\t\t\t#gallery-2 .gallery-item {\r\n\t\t\t\tfloat: left;\r\n\t\t\t\tmargin-top: 10px;\r\n\t\t\t\ttext-align: center;\r\n\t\t\t\twidth: 33%;\r\n\t\t\t}\r\n\t\t\t#gallery-2 img {\r\n\t\t\t\tborder: 2px solid #cfcfcf;\r\n\t\t\t}\r\n\t\t\t#gallery-2 .gallery-caption {\r\n\t\t\t\tmargin-left: 0;\r\n\t\t\t}\r\n\t\t<\/style>\r\n\t\t<!-- see gallery_shortcode() in wp-includes\/media.php -->\n\t\t<div id='gallery-2' class='gallery galleryid-57764 gallery-columns-3 gallery-size-full gallery1'><script type=\"text\/javascript\">\r\n\/\/ <![CDATA[\r\n\tjQuery(document).ready(function () {\r\n\t\tjQuery(\".gallery1 a\").attr(\"rel\",\"gallery1\");\t\r\n\t\tjQuery('a[rel=\"gallery1\"]').colorbox({maxWidth:\"95%\", maxHeight:\"95%\",title: function(){ return jQuery(this).children().attr(\"alt\"); }, });\r\n\t});\r\n\/\/ ]]>\r\n<\/script>\n<dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-10-04-at-4.51.36-PM-3.jpeg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-10-04-at-4.51.36-PM-3.jpeg\" width=\"740\" height=\"896\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 740px; --smush-placeholder-aspect-ratio: 740\/896;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-10-04-at-4.51.36-PM-1.jpeg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-10-04-at-4.51.36-PM-1.jpeg\" width=\"740\" height=\"893\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 740px; --smush-placeholder-aspect-ratio: 740\/893;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-10-04-at-4.51.36-PM-2.jpeg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-10-04-at-4.51.36-PM-2.jpeg\" width=\"740\" height=\"904\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 740px; --smush-placeholder-aspect-ratio: 740\/904;\" \/><\/a>\r\n<\/dt><\/dl><br style=\"clear: both\" \/>\r\n\t\t<\/div>\n\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La compa\u00f1\u00eda de lencer\u00eda sigue apostando por una nueva imagen y hoy se anima a celebrar a todo tipo de mujeres, alej\u00e1ndose de la perfecci\u00f3n que impuso por d\u00e9cadas. Durante los \u00faltimos a\u00f1os Victoria\u00b4s Secret (VS) sufri\u00f3 muchos cambios. Es que la gente se cans\u00f3 de sus \u00e1ngeles, de sus desfiles y del mensaje que [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":57771,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[234,100,30],"tags":[],"class_list":["post-57764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trend","category-noticias","category-moda"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/57764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=57764"}],"version-history":[{"count":0,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/57764\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media\/57771"}],"wp:attachment":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=57764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=57764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=57764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}