{"id":56150,"date":"2022-08-22T16:10:15","date_gmt":"2022-08-22T19:10:15","guid":{"rendered":"https:\/\/www.lasrosas.com.ar\/portal\/?p=56150"},"modified":"2022-08-22T16:10:29","modified_gmt":"2022-08-22T19:10:29","slug":"comienza-una-nueva-edicon-de-argentina-fashion-week","status":"publish","type":"post","link":"https:\/\/www.lasrosas.com.ar\/portal\/comienza-una-nueva-edicon-de-argentina-fashion-week\/","title":{"rendered":"COMIENZA UNA NUEVA EDIC\u00d3N DE ARGENTINA FASHION WEEK\u00a0"},"content":{"rendered":"<p>Del 22 al 26 de agosto se llevar\u00e1 a cabo una nueva edici\u00f3n del ARFW en el Palacio Paz. Se trata del principal encuentro de moda del pa\u00eds. C\u00f3mo ser\u00e1 esta gran puesta en escena.<\/p>\n<p class=\"paragraph\">M\u00e1s de\u00a0<b>15 importantes dise\u00f1adores argentinos<\/b>\u00a0participar\u00e1n<b>\u00a0del 22 al 26 de agosto del Argentina Fashion Week,<\/b>\u00a0el encuentro de moda m\u00e1s importante del pa\u00eds que organiza<b>\u00a0Vidal Rivas Producciones,<\/b>\u00a0bajo la direcci\u00f3n de\u00a0<b>H\u00e9ctor Vidal Rivas\u00a0<\/b>y equipo. Los desfiles se realizar\u00e1n\u00a0<b>en el Palacio Paz de la Ciudad de Buenos Aires.<\/b><\/p>\n<p class=\"paragraph\">\u00abSiempre es un honor trabajar conjuntamente con los dise\u00f1adores y las dise\u00f1adas en el marco de ARFW.\u00a0 Argentina es un gran terreno de talentos; mostrar aqu\u00ed y al mundo las creaciones de estos reconocidos dise\u00f1adores\u00a0<b>siempre es un motivo de celebraci\u00f3n\u201d,\u00a0<\/b>afirm\u00f3<b>\u00a0Vidal Rivas,\u00a0<\/b>asesor de imagen ic\u00f3nico de\u00a0<b>Mirtha Legrand<\/b>\u00a0y quien la acompa\u00f1a a todos los eventos sociales.<\/p>\n<p>Durante la primera jornada, los responsables en dar a conocer sus dise\u00f1os \u201cLuxury\u201d para la temporada primavera-verano son:\u00a0<b>Benito Fern\u00e1ndez, Marisa Marana, Mar\u00eda Pryor y Jorge Rey.\u00a0<\/b>Luego, ser\u00e1 el turno de<b>\u00a0Ver\u00f3nica de la Canal, Jean Pierre y Camila Romano.<\/b><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-56151 size-full lazyload\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-08-22-at-4.05.53-PM.jpeg\" alt=\"\" width=\"853\" height=\"1280\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-08-22-at-4.05.53-PM.jpeg 853w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-08-22-at-4.05.53-PM-640x960.jpeg 640w\" data-sizes=\"(max-width: 853px) 100vw, 853px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 853px; --smush-placeholder-aspect-ratio: 853\/1280;\" \/><\/p>\n<p class=\"paragraph\">Pero esto no es todo. Como si se tratara de una peque\u00f1a muestra de lo que ser\u00e1 una semana a pura moda, la pasarela estar\u00e1 colmada de federalismo argentino, con un interesante n\u00famero de dise\u00f1adores y dise\u00f1adoras provenientes de distintos puntos del pa\u00eds que har\u00e1n gala de sus creaciones y dejar\u00e1n, seguramente, a todos los asistentes asombrados.<\/p>\n<p class=\"paragraph\">En tanto, el d\u00eda 23 de agosto, ser\u00e1 el turno de\u00a0<b>Maribi, de C\u00f3rdoba; Francisco Ayala; Luis Palacios; Luis Guerra, de Santiago del Estero; Ana Tarrasanta, de Tres Arroyos; y Daniel Herrera.<\/b>\u00a0Pero este es solo el inicio de este extraordinario evento de la moda, el cual, hist\u00f3ricamente, no escatima en nombres de dise\u00f1adores y, por supuesto, derrocha estilo.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-56152 lazyload\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-08-22-at-4.07.16-PM.jpeg\" alt=\"\" width=\"662\" height=\"993\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-08-22-at-4.07.16-PM.jpeg 853w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-08-22-at-4.07.16-PM-640x960.jpeg 640w\" data-sizes=\"(max-width: 662px) 100vw, 662px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 662px; --smush-placeholder-aspect-ratio: 662\/993;\" \/><\/p>\n<p class=\"paragraph\">Pero esto no es todo. Como si se tratara de una peque\u00f1a muestra de lo que ser\u00e1 una semana a pura moda, la pasarela estar\u00e1 colmada de federalismo argentino, con un interesante n\u00famero de dise\u00f1adores y dise\u00f1adoras provenientes de distintos puntos del pa\u00eds que har\u00e1n gala de sus creaciones y dejar\u00e1n, seguramente, a todos los asistentes asombrados.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Del 22 al 26 de agosto se llevar\u00e1 a cabo una nueva edici\u00f3n del ARFW en el Palacio Paz. Se trata del principal encuentro de moda del pa\u00eds. C\u00f3mo ser\u00e1 esta gran puesta en escena. M\u00e1s de\u00a015 importantes dise\u00f1adores argentinos\u00a0participar\u00e1n\u00a0del 22 al 26 de agosto del Argentina Fashion Week,\u00a0el encuentro de moda m\u00e1s importante del [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":56154,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[234,100,30],"tags":[],"class_list":["post-56150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trend","category-noticias","category-moda"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/56150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=56150"}],"version-history":[{"count":0,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/56150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media\/56154"}],"wp:attachment":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=56150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=56150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=56150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}