{"id":49244,"date":"2022-03-26T11:07:54","date_gmt":"2022-03-26T14:07:54","guid":{"rendered":"https:\/\/www.lasrosas.com.ar\/portal\/?p=49244"},"modified":"2022-03-25T11:08:06","modified_gmt":"2022-03-25T14:08:06","slug":"evelin-liendo","status":"publish","type":"post","link":"https:\/\/www.lasrosas.com.ar\/portal\/evelin-liendo\/","title":{"rendered":"EVELIN LIENDO"},"content":{"rendered":"<p><i><span style=\"font-weight: 400;\">Una apasionada de su profesi\u00f3n en todas sus aristas: durante la ma\u00f1ana la vemos en TV, suena en Radio a la siesta y sigue cautivando con su voz en teatro. Villa Carlos Paz le abri\u00f3 sus puertas para darle vida a su voz como cantante en la obra 28 Rosas. Una nota en exclusiva con Evelin, la cordobesa activista por los derechos de los animales, que brilla con luz propia.\u00a0<\/span><\/i><\/p>\n<p><b>&#8211; Sos cantante y est\u00e1s haciendo temporada nuevamente en Carlos Paz \u00bfC\u00f3mo te llevas\u00a0con esa faceta tuya?\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u00a1Me encanta! Me formo en canto desde chica. A los 17 a\u00f1os decid\u00ed hacerlo de manera profesional con profes de canto y con t\u00e9cnicas vocales. Y como una cosa lleva a la otra, termin\u00e9 eligiendo como carrera Locuci\u00f3n Nacional. \u00a1La voz es magia!\u00a0<\/span><\/p>\n<p><img decoding=\"async\" class=\"wp-image-49247 aligncenter lazyload\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-02-07-at-2.41.54-PM.jpeg\" alt=\"\" width=\"631\" height=\"946\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-02-07-at-2.41.54-PM.jpeg 891w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/WhatsApp-Image-2022-02-07-at-2.41.54-PM-640x960.jpeg 640w\" data-sizes=\"(max-width: 631px) 100vw, 631px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 631px; --smush-placeholder-aspect-ratio: 631\/946;\" \/><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u201c\u00a1La voz es magia!\u201d<\/span><\/p><\/blockquote>\n<p><b>&#8211; Forman un elenco de lujo \u00bfC\u00f3mo es el detr\u00e1s de escena?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Te puedo contar el despu\u00e9s de escena: LA CENA (con rima y todo). La previa es pasar letra, repasar canciones, probar micr\u00f3fonos, charlar un poco, pero es m\u00e1s concentraci\u00f3n que otra cosa. El post show es comer algo rico, compartir, dialogar, tomar un vinito y carnear nuevas cosas.<\/span><\/p>\n<p><img decoding=\"async\" class=\"wp-image-49246 aligncenter lazyload\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/c.jpg\" alt=\"\" width=\"651\" height=\"690\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/c.jpg 1208w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/c-906x960.jpg 906w\" data-sizes=\"(max-width: 651px) 100vw, 651px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 651px; --smush-placeholder-aspect-ratio: 651\/690;\" \/><\/p>\n<p><b>&#8211; \u00bfQu\u00e9 sue\u00f1os quisieras cumplir en este rol?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u00a1Los que est\u00e9n a mi alcance y los que no tambi\u00e9n! Seguir conociendo de m\u00fasica y compartiendo momentos con profesionales del canto. Grabar m\u00e1s canciones, hacer alg\u00fan feat, seguir estudiando\u2026<\/span><\/p>\n<p><b>&#8211; Te vemos en ElDoce y te escuchamos en Radio Mitre, \u00bfsiempre quisiste ser Locutora?\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">No. Quer\u00eda ser actriz y abogada (seg\u00fan mam\u00e1). Cuando termin\u00e9 el secundario hice un test vocacional y dio como resultado 72 posibles carreras. Me gustaba de todo un poco. Fui tamizando hasta que encontr\u00e9 esta carrera de la rama de la comunicaci\u00f3n y me encant\u00f3. A los 21 a\u00f1os me recib\u00ed y fui contratada por mi querida Radio Mitre. Ya llevo aqu\u00ed 16 a\u00f1os y la verdad que la vida fue acomod\u00e1ndome en otros puestos y roles. En su momento tambi\u00e9n me anot\u00e9 en fonoaudiolog\u00eda, pero la tuve que dejar por falta de tiempo. Sin embargo, luego me fui acomodando y decid\u00ed seguir form\u00e1ndome. Este a\u00f1o me recibo de periodista.\u00a0<\/span><\/p>\n<p><img decoding=\"async\" class=\"wp-image-49248 aligncenter lazyload\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/X-e1648216966125.jpg\" alt=\"\" width=\"636\" height=\"478\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/X-e1648216966125.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/X-e1648216966125-640x480.jpg 640w\" data-sizes=\"(max-width: 636px) 100vw, 636px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 636px; --smush-placeholder-aspect-ratio: 636\/478;\" \/><\/p>\n<p><b>&#8211; \u00bfQu\u00e9 es lo que m\u00e1s te gusta de formar parte de los medios de C\u00f3rdoba?\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Me gusta poder ayudar. Desde los medios de comunicaci\u00f3n tengo la posibilidad de resolver problemas de las personas. Los periodistas tenemos contactos a los que mucha gente no puede llegar. Eso nos posiciona en otro lugar de lucha y por ende, de ayuda.\u00a0<\/span><\/p>\n<p><img decoding=\"async\" class=\"wp-image-49249 aligncenter lazyload\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/m.jpg\" alt=\"\" width=\"574\" height=\"219\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/m.jpg 1242w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/m-960x366.jpg 960w\" data-sizes=\"(max-width: 574px) 100vw, 574px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 574px; --smush-placeholder-aspect-ratio: 574\/219;\" \/><\/p>\n<p><b>&#8211; \u00a1En redes sociales demostr\u00e1s que sos perrera! \u00bfSent\u00eds que tu comunidad apoya tus ideales?\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Soy perrera, gatera, \u00a1animalera! Por suerte mi comunidad es hermosa y tiene muchhhhhhha empat\u00eda con estos seres maravillosos. No concibo que no apoyen los ideales de cuidado animal. Detesto el maltrato y no concilio con nadie que le haga da\u00f1o a un animalito. Puedo ponerme muy b\u00e9lica si observo que alguien le hace algo a una mascota. Amo encontrarles hogar a los animalitos abandonados y ayudo a las asociaciones y proteccionistas. \u00a1Deber\u00eda haber sido veterinaria! Pero ya estar\u00eda fundida (risas)<\/span><\/p>\n<p><img decoding=\"async\" class=\"wp-image-49250 aligncenter lazyload\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/LOGO9552.jpg\" alt=\"\" width=\"561\" height=\"842\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/LOGO9552.jpg 3456w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/LOGO9552-640x960.jpg 640w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/LOGO9552-1280x1920.jpg 1280w\" data-sizes=\"(max-width: 561px) 100vw, 561px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 561px; --smush-placeholder-aspect-ratio: 561\/842;\" \/><\/p>\n<p><b>&#8211; \u00bfC\u00f3mo te llevas con los haters?\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Mal. Pero me encargo de responderles por privado. Terminan pidiendo disculpas. Por suerte tampoco tengo tantos haters. Me dicen que deber\u00eda entender que como persona que trabaja en los medios estoy m\u00e1s expuesta. Igual eso no da derecho a que te insulten o hablen mal gratis. Alguien o algo te puede gustar o no. Desde el respeto se puede decir todo. Ahora cuando pasan esos l\u00edmites es necesario ubicarlos. Al menos esa es mi pol\u00edtica hoy. No se m\u00e1s adelante.\u00a0<\/span><\/p>\n<p><img decoding=\"async\" class=\"wp-image-49251 aligncenter lazyload\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/185462287_3895374953865166_2789405500040758708_n.jpg\" alt=\"\" width=\"452\" height=\"565\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/185462287_3895374953865166_2789405500040758708_n.jpg 1080w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/185462287_3895374953865166_2789405500040758708_n-768x960.jpg 768w\" data-sizes=\"(max-width: 452px) 100vw, 452px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 452px; --smush-placeholder-aspect-ratio: 452\/565;\" \/><\/p>\n<p><b>#PINGPONG<\/b><\/p>\n<p><b>\u00bfTv o radio? <\/b><span style=\"font-weight: 400;\">Los dos medios<\/span><\/p>\n<p><b>\u00bfCantar o grabar un spot? <\/b><span style=\"font-weight: 400;\">Cantar\u00a0<\/span><\/p>\n<p><b>\u00bfPerros o gatos?\u00a0 <\/b><span style=\"font-weight: 400;\">Perros, gatos, h\u00e1mster, p\u00e1jaros, conejos etc\u00a0<\/span><\/p>\n<p><b>\u00bfMakeup o cara lavada?\u00a0 <\/b><span style=\"font-weight: 400;\">Cara lavada\u00a0<\/span><\/p>\n<p><b>\u00bfJuntadas improvisadas o planeadas?\u00a0 <\/b><span style=\"font-weight: 400;\">Planeadas (soy insoportablemente organizada porque me quedan pocos tiempos libres)<\/span><\/p>\n<p><b>\u00bfUnos buenos mates o una buena taza de caf\u00e9? <\/b><span style=\"font-weight: 400;\">mates con yerba org\u00e1nica <\/span><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Una apasionada de su profesi\u00f3n en todas sus aristas: durante la ma\u00f1ana la vemos en TV, suena en Radio a la siesta y sigue cautivando con su voz en teatro. Villa Carlos Paz le abri\u00f3 sus puertas para darle vida a su voz como cantante en la obra 28 Rosas. Una nota en exclusiva con [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":49252,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[29,35,38],"tags":[],"class_list":["post-49244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","category-especiales","category-entrevistas"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/49244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=49244"}],"version-history":[{"count":0,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/49244\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media\/49252"}],"wp:attachment":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=49244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=49244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=49244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}