{"id":3645,"date":"2018-03-30T21:30:56","date_gmt":"2018-03-31T00:30:56","guid":{"rendered":"https:\/\/www.lasrosas.com.ar\/portal\/?p=3645"},"modified":"2018-04-05T15:08:40","modified_gmt":"2018-04-05T18:08:40","slug":"5-trending-topics-de-la-semana","status":"publish","type":"post","link":"https:\/\/www.lasrosas.com.ar\/portal\/5-trending-topics-de-la-semana\/","title":{"rendered":"#5 TRENDING TOPICS DE LA SEMANA"},"content":{"rendered":"<h3>Los temas m\u00e1s hablados esta semana, \u00a1te lo contamos ac\u00e1!<\/h3>\n<p><strong>#DESFILEARTEMIS<\/strong><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-3656 size-thumbnail\" src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/artemis-desfile-640x480.jpg\" alt=\"\" width=\"640\" height=\"480\" \/><\/p>\n<p><strong>Desfile en el \u201cfin de mundo\u201d:<\/strong> En un lugar donde no ocurre nada, pas\u00f3 Artemis y rompi\u00f3 el frio con el desfile de su \u00faltima colecci\u00f3n \u201cBulletproof\u201d, inspirado en sus ra\u00edces \u201cfueguinas\u201d. Ushuaia se visti\u00f3 elegante para recibir a este joven dise\u00f1ador, que patea estereotipos, demostrando, una vez m\u00e1s, que el talento y la edad no son directamente proporcional.<\/p>\n<p><strong>#GOODBYECAMERON<\/strong><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-3657 size-thumbnail\" src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/cameron-diaz-640x383.jpg\" alt=\"\" width=\"640\" height=\"383\" \/><\/p>\n<p><strong>Una sensual jubilada:<\/strong> Cameron D\u00edaz confirm\u00f3 su retiro de la actuaci\u00f3n. Desde el 2014 no ha participado en ning\u00fan proyecto cinematogr\u00e1fico. Para no ponernos melanc\u00f3licos, sabemos que tenemos sus inolvidables pel\u00edculas convertidas en cl\u00e1sicos de los canales los domingos. Es por esto que su rostro no se borrar\u00e1 tan f\u00e1cilmente.<\/p>\n<p><strong>#KATYYORLANDO<\/strong><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-3660 size-medium\" src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/katy-y-orlando-540x960.jpg\" alt=\"\" width=\"540\" height=\"960\" \/><\/p>\n<p><strong>Agarrados de la mano pero adentro de un disfraz:<\/strong> La famosa pareja, que volvi\u00f3 a juntarse, fue pillada en Tokio disfrazados de Luigi y Mario. \u00bfA qu\u00e9 estaban jugando?<\/p>\n<p><strong>#DOLORDEVISTA<\/strong><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-3659 size-thumbnail\" src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/el-busto-de-cristiano-640x473.jpg\" alt=\"\" width=\"640\" height=\"473\" \/><\/p>\n<p><strong>Un trabajo en boca de todos pero para tener bien lejos de los ojos:<\/strong> Un tributo realizado en honor a Cristiano Ronaldo en el Aeropuerto Internacional de Madeira termin\u00f3 generando burlas en vez de admiraci\u00f3n.<\/p>\n<p><strong>#ESONOESCRISTINA<\/strong><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-3658 size-medium\" src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/cristina-aguilera-635x960.jpg\" alt=\"\" width=\"635\" height=\"960\" srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/cristina-aguilera-635x960.jpg 635w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/cristina-aguilera.jpg 677w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/><\/p>\n<p><strong>Adivina adivinador, \u00bfqui\u00e9n es?:<\/strong> Christina Aguilera dej\u00f3 el maquillaje de lado, y mostr\u00f3 su rostro al natural en la portada de la revista \u201cPaper\u201d, donde habl\u00f3 de moda, sexualidad y del empoderamiento femenino.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Los temas m\u00e1s hablados esta semana, \u00a1te lo contamos ac\u00e1! #DESFILEARTEMIS Desfile en el \u201cfin de mundo\u201d: En un lugar donde no ocurre nada, pas\u00f3 Artemis y rompi\u00f3 el frio con el desfile de su \u00faltima colecci\u00f3n \u201cBulletproof\u201d, inspirado en sus ra\u00edces \u201cfueguinas\u201d. Ushuaia se visti\u00f3 elegante para recibir a este joven dise\u00f1ador, que patea [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":3661,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[100],"tags":[89,39,108,46,43,126,245],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/3645"}],"collection":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=3645"}],"version-history":[{"count":0,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/3645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media\/3661"}],"wp:attachment":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=3645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=3645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=3645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}