{"id":23917,"date":"2020-02-04T17:15:04","date_gmt":"2020-02-04T20:15:04","guid":{"rendered":"https:\/\/www.lasrosas.com.ar\/portal\/?p=23917"},"modified":"2020-02-04T17:15:04","modified_gmt":"2020-02-04T20:15:04","slug":"millie-bobby-brown-lanza-su-linea-de-maquillajes","status":"publish","type":"post","link":"https:\/\/www.lasrosas.com.ar\/portal\/millie-bobby-brown-lanza-su-linea-de-maquillajes\/","title":{"rendered":"MILLIE BOBBY BROWN LANZA SU L\u00cdNEA DE MAQUILLAJES"},"content":{"rendered":"<p><em><strong>Millie Bobby Brown presenta \u00abThe Florence by Mills 16 Wishes Collection\u00bb, su nueva l\u00ednea de maquillaje.<\/strong><\/em><\/p>\n<p>La actriz acaba de anunciar el lanzamiento de 16 productos nuevos, cada uno de ellos inspirados en los\u00a016 a\u00f1os\u00a0que cumplir\u00e1 el pr\u00f3ximo 19 de febrero. Sin embargo, la c\u00e1psula saldr\u00e1 a la venta online a partir del 03 de febrero de este a\u00f1o.\u00a0<em>\u201cCada uno de los\u00a016 deseos\u00a0representan cosas que yo valoro y creo. Los \u00faltimos meses han sido incre\u00edbles y estoy muy agradecida por c\u00f3mo ha acogido la gente \u2018Florence by Mills\u2019. Me encanta ver c\u00f3mo experimentan y juegan con los productos\u201d-<\/em> expres\u00f3 la actriz en un posteo de Instagram junto a un video publicitando la nueva noticia. Adem\u00e1s, se puede escuchar\u00a0la voz de Miley Cyrus hablando de estas\u00a0nuevas creaciones de maquillaje.<\/p>\n<p>La elecci\u00f3n del nombre de la l\u00ednea tiene que ver con un\u00a0homenaje a su bisabuela que se llamaba de esa forma y que representa de la mejor manera a la individualidad y al poder de ser ella misma. Algo de mayor importancia, es que todos los productos son veganos, libres de crueldad animal y est\u00e1n totalmente pensados para las pieles m\u00e1s j\u00f3venes.<\/p>\n\r\n\t\t<style type='text\/css'>\r\n\t\t\t#gallery-1 {\r\n\t\t\t\tmargin: auto;\r\n\t\t\t}\r\n\t\t\t#gallery-1 .gallery-item {\r\n\t\t\t\tfloat: left;\r\n\t\t\t\tmargin-top: 10px;\r\n\t\t\t\ttext-align: center;\r\n\t\t\t\twidth: 50%;\r\n\t\t\t}\r\n\t\t\t#gallery-1 img {\r\n\t\t\t\tborder: 2px solid #cfcfcf;\r\n\t\t\t}\r\n\t\t\t#gallery-1 .gallery-caption {\r\n\t\t\t\tmargin-left: 0;\r\n\t\t\t}\r\n\t\t<\/style>\r\n\t\t<!-- see gallery_shortcode() in wp-includes\/media.php -->\n\t\t<div id='gallery-1' class='gallery galleryid-23917 gallery-columns-2 gallery-size-medium gallery1'><script type=\"text\/javascript\">\r\n\/\/ <![CDATA[\r\n\tjQuery(document).ready(function () {\r\n\t\tjQuery(\".gallery1 a\").attr(\"rel\",\"gallery1\");\t\r\n\t\tjQuery('a[rel=\"gallery1\"]').colorbox({maxWidth:\"95%\", maxHeight:\"95%\",title: function(){ return jQuery(this).children().attr(\"alt\"); }, });\r\n\t});\r\n\/\/ ]]>\r\n<\/script>\n<dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/Screenshot_5970-e1580847238921.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/Screenshot_5970-960x640.jpg\" width=\"960\" height=\"640\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 960px; --smush-placeholder-aspect-ratio: 960\/640;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/rs_1024x754-190820085513-1024-millie-emd-082019-e1580847265319.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/rs_1024x754-190820085513-1024-millie-emd-082019-e1580847265319-960x645.jpg\" width=\"960\" height=\"645\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 960px; --smush-placeholder-aspect-ratio: 960\/645;\" \/><\/a>\r\n<\/dt><\/dl><br style=\"clear: both\" \/>\r\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Millie Bobby Brown presenta \u00abThe Florence by Mills 16 Wishes Collection\u00bb, su nueva l\u00ednea de maquillaje. La actriz acaba de anunciar el lanzamiento de 16 productos nuevos, cada uno de ellos inspirados en los\u00a016 a\u00f1os\u00a0que cumplir\u00e1 el pr\u00f3ximo 19 de febrero. Sin embargo, la c\u00e1psula saldr\u00e1 a la venta online a partir del 03 de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":23918,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[100,30],"tags":[],"class_list":["post-23917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-moda"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/23917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=23917"}],"version-history":[{"count":0,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/23917\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media\/23918"}],"wp:attachment":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=23917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=23917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=23917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}