{"id":19036,"date":"2019-09-23T15:34:50","date_gmt":"2019-09-23T18:34:50","guid":{"rendered":"https:\/\/www.lasrosas.com.ar\/portal\/?p=19036"},"modified":"2019-09-23T15:34:50","modified_gmt":"2019-09-23T18:34:50","slug":"dos-dias-a-pura-moda-en-paseo-del-jockey","status":"publish","type":"post","link":"https:\/\/www.lasrosas.com.ar\/portal\/dos-dias-a-pura-moda-en-paseo-del-jockey\/","title":{"rendered":"DOS D\u00cdAS A PURA MODA EN PASEO DEL JOCKEY"},"content":{"rendered":"<h4>El shopping de zona sur de la ciudad present\u00f3 las nuevas colecciones para la temporada primavera verano 2020 de las principales marcas que aglutina. Ayres, Portsaid, Las Oreiro, Ver, Kosiuko, Juanita Jo, XL, Lo que Ellas Quieren, Tejano y Batistella mostraron las tendencias SS20.<\/h4>\n<h4>Durante dos d\u00edas consecutivos, el Paseo del Jockey fue el centro de escena en la zona sur de la ciudad. Reuni\u00f3 a la comunidad de la moda para presentar las tendencias SS20 que ya est\u00e1 en marcha.<\/h4>\n<p>El jueves 19 fue el turno de Ayres, Kosiuko, Las Oreiro, Juanita Jo y Portsaid. Mientras que XL Extra Large, Tejano, Lo Que Ellas Quieren y Ver lucieron sus productos de la nueva temporada el viernes 20.<\/p>\n<p>AYRES fue la elegida para inaugurar la pasarela. Para la temporada Verano 2020, relanzaron las l\u00edneas de sastrer\u00eda -un cl\u00e1sico de la marca-, con un toque actual para acompa\u00f1ar la vida de la mujer moderna. Adem\u00e1s, sumaron n<\/p>\n\r\n\t\t<style type='text\/css'>\r\n\t\t\t#gallery-1 {\r\n\t\t\t\tmargin: auto;\r\n\t\t\t}\r\n\t\t\t#gallery-1 .gallery-item {\r\n\t\t\t\tfloat: left;\r\n\t\t\t\tmargin-top: 10px;\r\n\t\t\t\ttext-align: center;\r\n\t\t\t\twidth: 33%;\r\n\t\t\t}\r\n\t\t\t#gallery-1 img {\r\n\t\t\t\tborder: 2px solid #cfcfcf;\r\n\t\t\t}\r\n\t\t\t#gallery-1 .gallery-caption {\r\n\t\t\t\tmargin-left: 0;\r\n\t\t\t}\r\n\t\t<\/style>\r\n\t\t<!-- see gallery_shortcode() in wp-includes\/media.php -->\n\t\t<div id='gallery-1' class='gallery galleryid-19036 gallery-columns-3 gallery-size-large gallery1'><script type=\"text\/javascript\">\r\n\/\/ <![CDATA[\r\n\tjQuery(document).ready(function () {\r\n\t\tjQuery(\".gallery1 a\").attr(\"rel\",\"gallery1\");\t\r\n\t\tjQuery('a[rel=\"gallery1\"]').colorbox({maxWidth:\"95%\", maxHeight:\"95%\",title: function(){ return jQuery(this).children().attr(\"alt\"); }, });\r\n\t});\r\n\/\/ ]]>\r\n<\/script>\n<dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_1065-1920x1280.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_1065-1920x1280.jpg\" width=\"1920\" height=\"1280\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0852-1920x1280.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0852-1920x1280.jpg\" width=\"1920\" height=\"1280\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0893-1920x1280.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0893-1920x1280.jpg\" width=\"1920\" height=\"1280\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/a>\r\n<\/dt><\/dl><br style=\"clear: both\" \/><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0462-1280x1920.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0462-1280x1920.jpg\" width=\"1280\" height=\"1920\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1280px; --smush-placeholder-aspect-ratio: 1280\/1920;\" \/><\/a>\r\n<\/dt><\/dl>\r\n\t\t\t<br style='clear: both' \/>\r\n\t\t<\/div>\n\n<p>uevas l\u00edneas: Ayres\/Noche, Ayres\/Urbano y Ayres\/Valija.<\/p>\n<p>Romina Cardillo, su dise\u00f1adora, promueve el compromiso con la sustentabilidad, el medio ambiente y la producci\u00f3n de productos \u00e9ticos y amigables con la naturaleza. Un porcentaje de la colecci\u00f3n Verano 2020 est\u00e1 confeccionada con textiles 100% sustentables provenientes de Santa Constancia (Brasil), l\u00edder y pionero en la fabricaci\u00f3n de textiles amigables con el medio ambiente. Adem\u00e1s, Ayres ya no trabaja con pieles en sus colecciones. En su lugar, comenzaron a utilizar cueros ecol\u00f3gicos provenientes de Italia.<\/p>\n<p>El segundo lugar fue para KOSIUKO quien present\u00f3: What\u2019s BEYOND THE SEA? En un playa id\u00edlica y m\u00e1gica, esta marca propone para esta temporada looks imponentes y sofisticados, con dise\u00f1o \u00fanico que trasmiten tecnolog\u00eda, comodidad y libertad de movimiento y tejidos funcionales con est\u00e9tica vintage, que se mezclan en un festival de colores intensos, profundos, con estampas, degrad\u00e9 de batick y acentos vibrantes que retratan el esp\u00edritu de la marca.<\/p>\n<p>La tercer pasada fue para LAS OREIRO: \u201cViva el Taco\u201d se denomina la colecci\u00f3n primavera-verano 2020, la cual surgi\u00f3 de la inspiraci\u00f3n de la cultura mexicana. Universo de flores y una c\u00e1lida paleta de color se combinan con texturas de lino, raso y crepes, reinventando la silueta retro de los vestidos y prendas de la temporada que resaltan siempre la femineidad.<\/p>\n<p>Mediante estampas y bordados se reinterpretan elementos tradicionales mexicanos que conviven armoniosamente con diferentes prints de lunares y rayas tan caracter\u00edsticos del ADN Oreiro.<\/p>\n<p>Como novedad, proponen faldas de largo midi y la innovadora propuesta en la l\u00ednea de jeans con lavados complejos, que tambi\u00e9n suma propuesta de mini y shorts para los looks de alto verano.<\/p>\n<p>Por \u00faltimo, el cierre del jueves lo hizo PORTSAID, que present\u00f3 su nueva colecci\u00f3n inspirada en los cuatro elementos de la naturaleza: tierra, fuego, aire y agua.<\/p>\n<p>La l\u00ednea tierra, referida a los or\u00edgenes, transmite firmeza en tipolog\u00edas safari, con fibras naturales en tonalidades terrosas y verdes que se funden con colores vibrantes como el dij\u00f3n y el living coral. Un recorrido por el Amazonas vibrante: estampas selv\u00e1ticas, tropicales y del reino animal print. Las piezas fundamentales son las chaquetas militares, pantalones cargo, bermudas, camisas safari, monoprendas, vestidos chemise.<\/p>\n<p>&nbsp;<\/p>\n\r\n\t\t<style type='text\/css'>\r\n\t\t\t#gallery-2 {\r\n\t\t\t\tmargin: auto;\r\n\t\t\t}\r\n\t\t\t#gallery-2 .gallery-item {\r\n\t\t\t\tfloat: left;\r\n\t\t\t\tmargin-top: 10px;\r\n\t\t\t\ttext-align: center;\r\n\t\t\t\twidth: 33%;\r\n\t\t\t}\r\n\t\t\t#gallery-2 img {\r\n\t\t\t\tborder: 2px solid #cfcfcf;\r\n\t\t\t}\r\n\t\t\t#gallery-2 .gallery-caption {\r\n\t\t\t\tmargin-left: 0;\r\n\t\t\t}\r\n\t\t<\/style>\r\n\t\t<!-- see gallery_shortcode() in wp-includes\/media.php -->\n\t\t<div id='gallery-2' class='gallery galleryid-19036 gallery-columns-3 gallery-size-large gallery1'><script type=\"text\/javascript\">\r\n\/\/ <![CDATA[\r\n\tjQuery(document).ready(function () {\r\n\t\tjQuery(\".gallery1 a\").attr(\"rel\",\"gallery1\");\t\r\n\t\tjQuery('a[rel=\"gallery1\"]').colorbox({maxWidth:\"95%\", maxHeight:\"95%\",title: function(){ return jQuery(this).children().attr(\"alt\"); }, });\r\n\t});\r\n\/\/ ]]>\r\n<\/script>\n<dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0229-1920x1280.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0229-1920x1280.jpg\" width=\"1920\" height=\"1280\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0339-1920x1280.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0339-1920x1280.jpg\" width=\"1920\" height=\"1280\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0352-1920x1280.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0352-1920x1280.jpg\" width=\"1920\" height=\"1280\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/a>\r\n<\/dt><\/dl><br style=\"clear: both\" \/><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0386-1920x1280.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0386-1920x1280.jpg\" width=\"1920\" height=\"1280\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/a>\r\n<\/dt><\/dl>\r\n\t\t\t<br style='clear: both' \/>\r\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p>En cuanto a la l\u00ednea fuego, los tintes terrosos se combinan con los c\u00e1lidos del desierto y del atardecer, representando la energ\u00eda, la vitalidad y la expansi\u00f3n, donde sobresalen el algod\u00f3n hind\u00fa, la bambula, el lino cascarilla y el crochet. Los must: t\u00fanicas, kaftanes, monoprendas, chaquetas saharianas, pantalones con lazos, vestidos midi y largos, tejidos artesanales.<\/p>\n<p>El aire se simboliza a trav\u00e9s de colores suaves y apastelados, plasmados en prendas vaporosas y sedosas: voiles livianos, lino-viscosa, plumet\u00ed, guipiure, puntillas, crepes. Una reminiscencia post-rom\u00e1ntica y con influencia de los 90 se asoma a trav\u00e9s de bordados al tono, broderie y encaje.<\/p>\n<p>El blanco y los off-white, sin\u00f3nimos de estilo, elegancia y sencillez, se presentan en propuestas sutiles como pantalones amplios, kimonos, blusas, tejidos calados y prendas con volados.<\/p>\n<p>Por \u00faltimo, las costas de Biarritz inspiran esta l\u00ednea en una renovada propuesta n\u00e1utica, donde se imponen los trajes livianos a rayas, tops, faldas midi y vestidos largos con lazo. El agua salpica todo tipo de prendas que lucen el batik y el tie-dye, dando fluidez y frescura.<\/p>\n<p>En esta c\u00e1psula, donde predominan los tintes azules y las rayas marineras, el lino 100% y el Tencel son los protagonistas, y lo acompa\u00f1an tejidos con texturas nobles como flam\u00e9 lavado, morley, y bambulas de punto. El denim sigue triunfando y se presenta en pantalones culotte, bermudas largas, faldas, y en una infinidad de calces.<\/p>\n<p>El viernes 20 los desfiles se desarrollaron en la planta baja del Paseo del Jockey. En este d\u00eda, las modelos lucieron las prendas de Ver, Lo que Ellas Quieren, XL Extra Large y Tejano; junto con el calzado de BATISTELLA, quien adelant\u00f3 que las grandes protagonistas de los d\u00edas calor ser\u00e1n las sandalias planas, que adem\u00e1s de ser muy c\u00f3modas, se adaptan a todos los looks de verano, desde shorts, monos, vestidos hasta faldas midi.<\/p>\n\r\n\t\t<style type='text\/css'>\r\n\t\t\t#gallery-3 {\r\n\t\t\t\tmargin: auto;\r\n\t\t\t}\r\n\t\t\t#gallery-3 .gallery-item {\r\n\t\t\t\tfloat: left;\r\n\t\t\t\tmargin-top: 10px;\r\n\t\t\t\ttext-align: center;\r\n\t\t\t\twidth: 33%;\r\n\t\t\t}\r\n\t\t\t#gallery-3 img {\r\n\t\t\t\tborder: 2px solid #cfcfcf;\r\n\t\t\t}\r\n\t\t\t#gallery-3 .gallery-caption {\r\n\t\t\t\tmargin-left: 0;\r\n\t\t\t}\r\n\t\t<\/style>\r\n\t\t<!-- see gallery_shortcode() in wp-includes\/media.php -->\n\t\t<div id='gallery-3' class='gallery galleryid-19036 gallery-columns-3 gallery-size-large gallery1'><script type=\"text\/javascript\">\r\n\/\/ <![CDATA[\r\n\tjQuery(document).ready(function () {\r\n\t\tjQuery(\".gallery1 a\").attr(\"rel\",\"gallery1\");\t\r\n\t\tjQuery('a[rel=\"gallery1\"]').colorbox({maxWidth:\"95%\", maxHeight:\"95%\",title: function(){ return jQuery(this).children().attr(\"alt\"); }, });\r\n\t});\r\n\/\/ ]]>\r\n<\/script>\n<dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0126-1920x1280.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_0126-1920x1280.jpg\" width=\"1920\" height=\"1280\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_9919-1920x1280.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_9919-1920x1280.jpg\" width=\"1920\" height=\"1280\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/a>\r\n<\/dt><\/dl><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_9875-1920x1280.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_9875-1920x1280.jpg\" width=\"1920\" height=\"1280\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/a>\r\n<\/dt><\/dl><br style=\"clear: both\" \/><dl class=\"gallery-item\">\n<dt class=\"gallery-icon\">\r\n<a href=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_9827-1920x1280.jpg\" title=\"\" rel=\"gallery1\"><img decoding=\"async\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/DSC_9827-1920x1280.jpg\" width=\"1920\" height=\"1280\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/1280;\" \/><\/a>\r\n<\/dt><\/dl>\r\n\t\t\t<br style='clear: both' \/>\r\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p>La tendencia ugly sigue apareciendo en esta temporada de la mano de las \u201cugly sandals\u201d, una combinaci\u00f3n de confort y dise\u00f1o que est\u00e1 siendo furor. Se llevan muy bien con vestidos y estampados de verano, ya que cuanto m\u00e1s contraste tenga el outfit, m\u00e1s trendy ser\u00e1.<\/p>\n<p>Tambi\u00e9n vemos que las zapatillas llegaron para combinarse con todos los estilos de la temporada. Zapatillas blancas, con detalles de estampado reptil, ugly shoes, sneakers o las cl\u00e1sicas de lona, todas est\u00e1n permitidas y las vas a ver por todos lados en las calles.<\/p>\n<p>Por \u00faltimo, de a poco vamos a volver a ver las sandalias con el cl\u00e1sico taco cuadrado. Son s\u00faper tendenciosas, estilizan y son tan vers\u00e1tiles que se adaptan s\u00faper bien a outfits tanto de d\u00eda como de noche.<\/p>\n<p>Con show, m\u00fasica en vivo de Las Rositas &#8211; tango electr\u00f3nico &#8211; y una puesta en escena interactiva con mucho contenido, Paseo del Jockey organiz\u00f3 una presentaci\u00f3n super atractiva donde rein\u00f3 el dinamismo entre la circulaci\u00f3n de modelos y el p\u00fablico en todo el centro comercial.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El shopping de zona sur de la ciudad present\u00f3 las nuevas colecciones para la temporada primavera verano 2020 de las principales marcas que aglutina. Ayres, Portsaid, Las Oreiro, Ver, Kosiuko, Juanita Jo, XL, Lo que Ellas Quieren, Tejano y Batistella mostraron las tendencias SS20. Durante dos d\u00edas consecutivos, el Paseo del Jockey fue el centro [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":19053,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[30],"tags":[],"class_list":["post-19036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-moda"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/19036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=19036"}],"version-history":[{"count":0,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/19036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media\/19053"}],"wp:attachment":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=19036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=19036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=19036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}