{"id":15953,"date":"2019-06-18T10:55:32","date_gmt":"2019-06-18T13:55:32","guid":{"rendered":"https:\/\/www.lasrosas.com.ar\/portal\/?p=15953"},"modified":"2019-06-18T10:55:32","modified_gmt":"2019-06-18T13:55:32","slug":"loccitane-presenta-la-coleccion-lhomme-cologne-cedrat","status":"publish","type":"post","link":"https:\/\/www.lasrosas.com.ar\/portal\/loccitane-presenta-la-coleccion-lhomme-cologne-cedrat\/","title":{"rendered":"L&#8217;OCCITANE PRESENTA LA COLECCI\u00d3N L&#8217;HOMME COLOGNE CEDRAT"},"content":{"rendered":"<h3><strong>Para este D\u00eda del Padre, L\u2019Occitane te propone los productos de la colecci\u00f3n L\u2019Homme Cologne Cedrat<\/strong><\/h3>\n<p><strong><em>UNA HISTORIA AUT\u00c9NTICA<\/em><\/strong><\/p>\n<p>La poderosa huella de un hombre con mil facetas. Cologne C\u00e9drat para hombre es el perfume de un hombre apasionado por la libertad. Con la mirada perdida en el horizonte, toma el mar. Determinado, zarpa hacia un viaje c\u00edtrico y acu\u00e1tico, para encontrarse a s\u00ed mismo. El hombre Cologne C\u00e9drat tiene sus ra\u00edces en Arl\u00e9s. Aunque est\u00e9 situada en las orillas del R\u00f3dano, Arl\u00e9s era a la vez un importante puerto fluvial y mar\u00edtimo. La vida de marinero pasaba de padres a hijos. Hombres orgullosos y libres que han construido la historia de la Provenza.<\/p>\n<p><em><strong>EAU DE TOILETTE L\u2019HOMME COLOGNE CEDRAT<\/strong><\/em><\/p>\n<p>El Eau de Toilette Cologne C\u00e9drat para el hombre sin ataduras, encarna la evasi\u00f3n a un horizonte sin l\u00edmites, en la que se mezclan un frescor de la bruma marina con la c\u00e1scara del fruto del c\u00e9drat. Un c\u00f3ctel c\u00edtrico, vibrante y acu\u00e1tico sobre un fondo turbador de especias amaderadas.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-15956 lazyload\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/LANCOME-3-960x960.jpg\" alt=\"\" width=\"960\" height=\"960\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/LANCOME-3-960x960.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/LANCOME-3-1920x1920.jpg 1920w\" data-sizes=\"(max-width: 960px) 100vw, 960px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 960px; --smush-placeholder-aspect-ratio: 960\/960;\" \/><\/p>\n<p><em><strong>EL PERFUME<\/strong><\/em><\/p>\n<p>Una fragancia con car\u00e1cter, masculina y refrescante, Cologne C\u00e9drat para hombre es el encuentro de las notas c\u00edtricas del c\u00e9drat y las notas refrescantes de la menta con las especias fr\u00edas. En cabeza, la c\u00e1scara del c\u00e9drat y la menta g\u00e9lida refrescan el aire c\u00e1lido de Provenza. Un acorde fresco y acu\u00e1tico que se prolonga en el coraz\u00f3n al posarse sobre la piel con una estela masculina de hojas de violeta y de lavanda. El jengibre, la pimienta negra y las bayas rojas llegan para apimentar el acorde. Por \u00faltimo las notas profundas y amaderadas de cedro, \u00e1mbar y almizcle aten\u00faan el fuerte car\u00e1cter de esta fragancia. Un aceite esencial de c\u00e9drat de C\u00f3rcega llega para realzar las notas amargas de la c\u00e1scara en este perfume.<\/p>\n<p><em><strong>LAS PALABRAS DEL PERFUMISTA<\/strong><\/em><\/p>\n<p>\u00abHe imaginado el hombre Cologne C\u00e9drat como un hombre luminoso, natural, temperamental e instintivo, reflejando el frescor incisivo y chispeante de este perfume. Me gusta escaparme al Mediterr\u00e1neo, explorar nuevos horizontes. Me gusta el ritmo de vida que reina all\u00ed\u00bb. Julie Mass\u00e9<\/p>\n<p><em><strong>EL FRASCO<\/strong><\/em><\/p>\n<p>Con su curva dulce y sus aristas rectas, el frasco met\u00e1lico evoca a primera vista un objeto eminentemente masculino.<\/p>\n<p><em><strong>PRECIO<\/strong><\/em><br \/>\n$3.452<\/p>\n<p><em><strong>GEL DE DUCHA L\u2019HOMME COLOGNE CEDRAT<\/strong><\/em><\/p>\n<p>M\u00e1s que una ducha refrescante. Un momento de escape&#8230; Este Gel de Ducha limpia el cuerpo y el pelo. Su espuma generosa deja la piel fresca y delicadamente perfumada con las notas c\u00edtricas y acu\u00e1ticas de la L&#8217;Homme Cologne C\u00e9drat para Hombre. Un c\u00f3ctel c\u00edtrico y vibrante sobre un fondo de especias amaderadas.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-15954 lazyload\" data-src=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/LANCOME-1-960x960.jpg\" alt=\"\" width=\"960\" height=\"960\" data-srcset=\"https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/LANCOME-1-960x960.jpg 960w, https:\/\/www.lasrosas.com.ar\/portal\/wp-content\/uploads\/LANCOME-1-1920x1920.jpg 1920w\" data-sizes=\"(max-width: 960px) 100vw, 960px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 960px; --smush-placeholder-aspect-ratio: 960\/960;\" \/><\/p>\n<p><em><strong>EL PERFUME<\/strong><\/em><\/p>\n<p>El Gel de Ducha est\u00e1 sutilmente perfumado con las notas refrescantes y masculinas de la L&#8217;Homme Cologne C\u00e9drat para Hombre. Este perfume c\u00edtrico y arom\u00e1tico asocia a la c\u00e1scara del C\u00e9drat con el frescor de la bruma marina. Las notas especiadas y arom\u00e1ticas se posan sobre una profunda estela amaderada de cedro, \u00e1mbar y almizcle. El perfume se ha compuesto alrededor de un aceite esencial de c\u00e9drat que refuerza su frescor y naturalidad.<\/p>\n<p><em><strong>EL DISE\u00d1O<\/strong><\/em><\/p>\n<p>Este pr\u00e1ctico frasco te\u00f1ido de azul profundo se viste con un motivo de madera flotante.<\/p>\n<p><em><strong>PRECIO<\/strong><\/em><br \/>\n$1.131<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Para este D\u00eda del Padre, L\u2019Occitane te propone los productos de la colecci\u00f3n L\u2019Homme Cologne Cedrat UNA HISTORIA AUT\u00c9NTICA La poderosa huella de un hombre con mil facetas. Cologne C\u00e9drat para hombre es el perfume de un hombre apasionado por la libertad. Con la mirada perdida en el horizonte, toma el mar. Determinado, zarpa hacia [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":15955,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[30],"tags":[],"class_list":["post-15953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-moda"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/15953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=15953"}],"version-history":[{"count":0,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/posts\/15953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media\/15955"}],"wp:attachment":[{"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=15953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=15953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasrosas.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=15953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}